{"id":147,"count":17,"description":"100 Notas de lanzamiento","link":"https:\/\/axosnet.info\/es\/docs\/es-notas\/","name":"Notas Recientes","slug":"es-notas","taxonomy":"knowledge_base","parent":0,"meta":[],"subcategories_count":0,"total_docs_count":5,"last_updated_time":"27 de abril de 2026","thumbnail":"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/es-rn-icon-2.webp","_links":{"self":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/knowledge_base\/147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/knowledge_base"}],"about":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/taxonomies\/knowledge_base"}],"wp:post_type":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs?knowledge_base=147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}