{"id":9751,"date":"2023-02-22T20:44:41","date_gmt":"2023-02-22T20:44:41","guid":{"rendered":"https:\/\/rfiii.com\/?post_type=docs&#038;p=9751"},"modified":"2023-08-14T21:25:57","modified_gmt":"2023-08-14T21:25:57","password":"","slug":"quickconnect-aec-con-credenciales-acs","status":"publish","type":"docs","link":"https:\/\/axosnet.info\/es\/docs\/quickconnect-aec-con-credenciales-acs\/","title":{"rendered":"Conexi\u00f3n r\u00e1pida mediante las credenciales de ACS"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"9751\" class=\"elementor elementor-9751 elementor-6741\" data-elementor-post-type=\"docs\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3e733efe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3e733efe\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-281f893b\" data-id=\"281f893b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ae68878 elementor-widget elementor-widget-text-editor\" data-id=\"6ae68878\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p>\n<p>Esta secci\u00f3n lo gu\u00eda a trav\u00e9s de tres formas de realizar una conexi\u00f3n r\u00e1pida entre Axosnet ERP Connector (AEC) y Concur. La conexi\u00f3n adecuada depende de la configuraci\u00f3n de la empresa, y el administrador de SAP solo lo hace cuando comienza a usar AEC. Si no es cliente de Axosnet, considere solicitar informaci\u00f3n haciendo clic en el enlace &#8220;Solicitar informaci\u00f3n&#8221;.<\/p>\n<p>El primer m\u00e9todo es usar las Credenciales de ACS. Siga los pasos a continuaci\u00f3n.<\/p>\n<p>1. Haga clic en el bot\u00f3n &#8220;Conectar&#8221;.<\/p>\n<p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/02\/aerpc-B.a.1.png\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/02\/aerpc-B.a.1.png\" width=\"1024\" height=\"488\"><\/a><\/p>\n<ol><\/ol>\n<p><\/p>\n<p><br><\/p>\n<p>2. Aparecer\u00e1 una ventana emergente de &#8220;T\u00c9RMINOS Y CONDICIONES&#8221;, marque la casilla de verificaci\u00f3n &#8220;Informaci\u00f3n compartida&#8221; y haga clic en el bot\u00f3n &#8220;Acepto&#8221;.<\/p>\n<p><br><\/p>\n<p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/02\/aerpc-B.a.2.png\"><img decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/02\/aerpc-B.a.2.png\" width=\"1024\" height=\"479\"><\/a><\/p>\n<p><\/p>\n<p><br><\/p>\n<p>3. Aparecer\u00e1 la ventana \u201cAxosnet Middleware\u201d.<\/p>\n<p><br><\/p>\n<p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/02\/aerpc-B.a.3.png\"><img decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/02\/aerpc-B.a.3.png\" width=\"1024\" height=\"489\"><\/a><\/p>\n<p><\/p>\n<p><br><\/p>\n<p>4. Maximice la ventana. En la secci\u00f3n &#8220;Preferencias&#8221;, puede cambiar el idioma con el que desea trabajar desde el men\u00fa desplegable &#8220;Idioma&#8221;. De forma predeterminada, el idioma est\u00e1 configurado en ingl\u00e9s.<\/p>\n<p><br><\/p>\n<p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/02\/aerpc-B.a.4.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/02\/aerpc-B.a.4.png\" width=\"1024\" height=\"546\"><\/a><\/p>\n<p><\/p>\n<p><br><\/p>\n<p>5. Seleccione el entorno en el que desea trabajar desde el men\u00fa desplegable &#8220;Seleccione un entorno para conectarse&#8221;.<\/p>\n<p><br><\/p>\n<p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/02\/aerpc-B.a.5.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/02\/aerpc-B.a.5.png\" width=\"1024\" height=\"542\"><\/a><\/p>\n<p><\/p>\n<p><br><\/p>\n<p>6. Escriba el correo electr\u00f3nico de su usuario en el campo &#8220;Ingrese la cuenta del entorno de Axosnet Cloud Solutions para continuar&#8221;. Luego, haga clic en el bot\u00f3n &#8220;Siguiente&#8221;.<\/p>\n<p><br><\/p>\n<p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/02\/aerpc-B.a.6.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/02\/aerpc-B.a.6.png\" width=\"1024\" height=\"540\"><\/a><\/p>\n<p><\/p>\n<p><br><\/p>\n<p>7. El sistema detectar\u00e1 que utiliza sus credenciales de ACS para iniciar sesi\u00f3n en la plataforma de ACS. Escriba sus credenciales de ACS. Haga clic en el bot\u00f3n &#8220;Enviar&#8221;.<\/p>\n<p><br><\/p>\n<p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/02\/aerpc-B.a.7.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/02\/aerpc-B.a.7.png\" width=\"1024\" height=\"541\"><\/a><\/p>\n<p><\/p>\n<p><br><\/p>\n<p>8. Ser\u00e1 redirigido a una pantalla con un mensaje de \u00e9xito.<\/p>\n<p><br><\/p>\n<p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/02\/aerpc-B.a.8.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/02\/aerpc-B.a.8.png\" width=\"1024\" height=\"541\"><\/a><\/p>\n<p><\/p>\n<p><br><\/p>\n<p>9. Cierre la pantalla Axosnet Middleware. Mire la marca de verificaci\u00f3n verde seguida del estado &#8220;Conectado&#8221;, y debajo de esta l\u00ednea, tendr\u00e1 el bot\u00f3n &#8220;Desconectar&#8221; (en lugar del anterior bot\u00f3n &#8220;Conectar&#8221;).<\/p>\n<p><br><\/p>\n<p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/02\/aerpc-B.a.9.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/02\/aerpc-B.a.9.png\" width=\"1024\" height=\"490\"><\/a><\/p>\n<p><\/p>\n<p><br><\/p>\n<p>10. Cuando desee desvincular, haga clic en el bot\u00f3n &#8220;Desconectar&#8221;.<\/p>\n<p><br><\/p>\n<p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/02\/aerpc-B.a.10.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/02\/aerpc-B.a.10.png\" width=\"1024\" height=\"486\"><\/a><\/p>\n<p><\/p>\n<p><br><\/p>\n<p>11. Aparecer\u00e1 una ventana de confirmaci\u00f3n que le preguntar\u00e1 si desea desconectarse de SAP Concur; haga clic en el bot\u00f3n &#8220;S\u00ed&#8221; para continuar o &#8220;No&#8221; para cancelar la operaci\u00f3n.<\/p><p><br><\/p>\n<p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/02\/aerpc-B.a.11.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/02\/aerpc-B.a.11.png\" width=\"1024\" height=\"482\"><\/a><\/p>\n<p><\/p>\n<p><br><\/p><p>12. Finalmente, mostrar\u00e1 una notificaci\u00f3n que confirma que se ha desconectado correctamente de la aplicaci\u00f3n. En el segundo plano, mire el bot\u00f3n que ya ha cambiado a &#8220;Conectar&#8221;. Cierre la ventana haciendo clic en el bot\u00f3n &#8220;Ok&#8221;.<\/p><p><br><\/p>\n<p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/02\/aerpc-B.a.12.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/02\/aerpc-B.a.12.png\" width=\"1024\" height=\"487\"><\/a><\/p>\n<p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Esta secci\u00f3n lo gu\u00eda a trav\u00e9s de tres formas de realizar una conexi\u00f3n r\u00e1pida entre Axosnet ERP Connector (AEC) y Concur. La conexi\u00f3n adecuada depende de la configuraci\u00f3n de la empresa, y el administrador de SAP solo lo hace cuando comienza a usar AEC. Si no es cliente de Axosnet, considere solicitar informaci\u00f3n haciendo clic [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":"","footnotes":""},"doc_category":[161],"doc_tag":[],"knowledge_base":[143],"class_list":["post-9751","docs","type-docs","status-publish","hentry","doc_category-es-aerpc-qc-login","knowledge_base-es-para-factura-gastos"],"year_month":"2026-07","word_count":357,"total_views":"78","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"","author_nicename":"","author_url":"https:\/\/axosnet.info\/es\/author\/"},"doc_category_info":[{"term_name":"Inicio de sesi\u00f3n de QuickConnect","term_url":"https:\/\/axosnet.info\/es\/docs\/es-para-factura-gastos\/es-aerpc-qc-login\/"}],"doc_tag_info":[],"knowledge_base_info":[{"term_name":"Conector Axosnet ERP para Factura\/Gastos","term_url":"https:\/\/axosnet.info\/es\/docs\/es-para-factura-gastos\/","term_slug":"es-para-factura-gastos"}],"knowledge_base_slug":["es-para-factura-gastos"],"_links":{"self":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/9751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/comments?post=9751"}],"version-history":[{"count":16,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/9751\/revisions"}],"predecessor-version":[{"id":12932,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/9751\/revisions\/12932"}],"wp:attachment":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/media?parent=9751"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/doc_category?post=9751"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/doc_tag?post=9751"},{"taxonomy":"knowledge_base","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/knowledge_base?post=9751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}