{"id":9746,"date":"2023-02-22T04:16:05","date_gmt":"2023-02-22T04:16:05","guid":{"rendered":"https:\/\/rfiii.com\/?post_type=docs&#038;p=9746"},"modified":"2023-08-09T03:29:02","modified_gmt":"2023-08-09T03:29:02","password":"","slug":"obtenga-el-conector-axosnet-erp-aec","status":"publish","type":"docs","link":"https:\/\/axosnet.info\/es\/docs\/obtenga-el-conector-axosnet-erp-aec\/","title":{"rendered":"Obtenga Axosnet ERP Connector (AEC)"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"9746\" class=\"elementor elementor-9746 elementor-6625\" data-elementor-post-type=\"docs\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3ab57dbd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3ab57dbd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1b4ad1f6\" data-id=\"1b4ad1f6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14c31888 elementor-widget elementor-widget-text-editor\" data-id=\"14c31888\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El conector Axosnet ERP para Concur Expense automatiza el reembolso y la contabilidad de viajes y gastos en su SAP ERP. El conector Axosnet ERP para Concur Invoice integra la nube en su proceso de verificaci\u00f3n de facturas SAP ERP.<\/p><p>En primer lugar, para comenzar a utilizar Axosnet ERP Connector for Expense o Axosnet Connect for Invoice, debe obtener la aplicaci\u00f3n de la plataforma SAP Concur; los siguientes pasos le ayudar\u00e1n a realizar la tarea.<\/p><p>1. En la p\u00e1gina de inicio de SAP Concur, haga clic en &#8220;Centro de Aplicaciones&#8221;.<\/p><p>\u00a0<\/p><p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/02\/aerpc-A.a.1.png\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/02\/aerpc-A.a.1.png\" width=\"1919\" height=\"910\" \/><\/a><\/p><p>\u00a0<\/p><p>2. Escriba Axosnet ERP para gastos o Axosnet ERP para facturas en el cuadro de b\u00fasqueda en la parte superior derecha de la pantalla. Haga clic en &#8220;Buscar&#8221;.<\/p><p>\u00a0<\/p><p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/02\/aerpc-A.a.2.png\"><img decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/02\/aerpc-A.a.2.png\" width=\"1919\" height=\"912\" \/><\/a><\/p><p>\u00a0<\/p><p>3. Procedamos con Axosnet ERP para gastos para nuestra demostraci\u00f3n; una vez que la soluci\u00f3n est\u00e9 en la pantalla, haga clic en ella.<\/p><p>\u00a0<\/p><p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/02\/aerpc-A.a.3.png\"><img decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/02\/aerpc-A.a.3.png\" width=\"1919\" height=\"912\" \/><\/a><\/p><p><strong>Nota<\/strong>: El nombre de la aplicaci\u00f3n cambiar\u00e1 seg\u00fan la versi\u00f3n que busque.<\/p><p>\u00a0<\/p><p>4. Acceder\u00e1 a la p\u00e1gina de solicitud de AEC. Haga clic en el enlace &#8220;Solicitar informaci\u00f3n&#8221; (debajo del bot\u00f3n Conectar) para ser redirigido a un formulario de SAP Concur.<\/p><p>\u00a0<\/p><p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/02\/aerpc-A.a.4.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/02\/aerpc-A.a.4.png\" width=\"1919\" height=\"915\" \/><\/a><\/p><p>\u00a0<\/p><p>5. Para solicitar una demostraci\u00f3n. Por favor complete el formulario y env\u00edelo. El \u00e1rea comercial se comunicar\u00e1 con usted en breves momentos.<\/p><p>\u00a0<\/p><p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/02\/aerpc-A.a.5-1.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/02\/aerpc-A.a.5-1.png\" width=\"1919\" height=\"913\" \/><\/a><\/p><p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/02\/aerpc-A.a.5-2.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/02\/aerpc-A.a.5-2.png\" width=\"1918\" height=\"911\" \/><\/a><\/p><p>Una vez que hayas instalado la aplicaci\u00f3n AEC, podr\u00e1s disfrutar de todos los beneficios que ofrece.<\/p><p>\u00a0<\/p><p><strong>Importante<\/strong>: Si es un cliente nuevo, tenga en cuenta que la activaci\u00f3n completa significa que se ha establecido la conexi\u00f3n entre Axosnet ERP Connector y Concur; ahora nuestro Gerente de Proyecto puede contactarlo para instalar el C\u00f3digo SAP y activar los flujos de datos que necesita. Si necesita m\u00e1s ayuda, comun\u00edquese con el servicio de atenci\u00f3n al cliente de Axosnet<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>El conector Axosnet ERP para Concur Expense automatiza el reembolso y la contabilidad de viajes y gastos en su SAP ERP. El conector Axosnet ERP para Concur Invoice integra la nube en su proceso de verificaci\u00f3n de facturas SAP ERP. En primer lugar, para comenzar a utilizar Axosnet ERP Connector for Expense o Axosnet Connect [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":"","footnotes":""},"doc_category":[142],"doc_tag":[],"knowledge_base":[143],"class_list":["post-9746","docs","type-docs","status-publish","hentry","doc_category-es-aerpc-empezando","knowledge_base-es-para-factura-gastos"],"year_month":"2026-05","word_count":298,"total_views":"58","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"","author_nicename":"","author_url":"https:\/\/axosnet.info\/es\/author\/"},"doc_category_info":[{"term_name":"Comenzando Connector ERP","term_url":"https:\/\/axosnet.info\/es\/docs\/es-para-factura-gastos\/es-aerpc-empezando\/"}],"doc_tag_info":[],"knowledge_base_info":[{"term_name":"Conector Axosnet ERP para Factura\/Gastos","term_url":"https:\/\/axosnet.info\/es\/docs\/es-para-factura-gastos\/","term_slug":"es-para-factura-gastos"}],"knowledge_base_slug":["es-para-factura-gastos"],"_links":{"self":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/9746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/comments?post=9746"}],"version-history":[{"count":10,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/9746\/revisions"}],"predecessor-version":[{"id":12280,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/9746\/revisions\/12280"}],"wp:attachment":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/media?parent=9746"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/doc_category?post=9746"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/doc_tag?post=9746"},{"taxonomy":"knowledge_base","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/knowledge_base?post=9746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}