{"id":9571,"date":"2023-01-31T19:54:42","date_gmt":"2023-01-31T19:54:42","guid":{"rendered":"https:\/\/rfiii.com\/?post_type=docs&#038;p=9571"},"modified":"2025-10-16T16:13:39","modified_gmt":"2025-10-16T16:13:39","password":"","slug":"consulta-de-deposito-de-axosnet","status":"publish","type":"docs","link":"https:\/\/axosnet.info\/es\/docs\/consulta-de-deposito-de-axosnet\/","title":{"rendered":"Consulta del Bucket de Axosnet"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"9571\" class=\"elementor elementor-9571 elementor-6277\" data-elementor-post-type=\"docs\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1621a309 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1621a309\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5ba6cff4\" data-id=\"5ba6cff4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37428f59 elementor-widget elementor-widget-text-editor\" data-id=\"37428f59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Una vez ejecutado un trabajo, localizar\u00e1 y extraer\u00e1 la informaci\u00f3n especificada en el momento de su programaci\u00f3n y la depositar\u00e1 en un Bucket que podr\u00e1 consultar de la siguiente forma:<\/p><p>1. Inicie sesi\u00f3n en la plataforma Axosnet Cloud Solutions\u00ae e ingrese a la aplicaci\u00f3n Axosnet Reporting V2.0.<\/p><p><b>Nota<\/b>: Si necesita m\u00e1s informaci\u00f3n, consulte el Manual ACS, secci\u00f3n <a href=\"https:\/\/axosnet.info\/docs\/default-login-2\/\">Inicio de sesi\u00f3n<\/a>.<\/p><p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/FET-A.b.1.png\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/FET-A.b.1.png\" width=\"1600\" height=\"752\" \/><\/a><\/p><p>2. Llegar\u00e1 a la p\u00e1gina de Axosnet Bucket.<\/p><p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/FET-A.b.2.jpg\"><img decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/FET-A.b.2.jpg\" width=\"1000\" height=\"468\" \/><\/a><\/p><p>3. Haga clic en la carpeta principal para mostrar las subcarpetas. Todas las carpetas se mostrar\u00e1n con la nomenclatura de a\u00f1o, mes, d\u00eda, hora, minuto y segundo. Seleccione la carpeta que desea consultar.<\/p><p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/FET-A.b.3.jpg\"><img decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/FET-A.b.3.jpg\" width=\"1000\" height=\"482\" \/><\/a><\/p><p>4. La carpeta seleccionada contendr\u00e1 los CFDi\u00b4s que fueron encontrados en el periodo de postulaci\u00f3n. Al hacer clic con el bot\u00f3n derecho en la carpeta, podemos descargarla, eliminarla, renombrarla, actualizarla o copiarla.<\/p><p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/FET-A.b.4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/FET-A.b.4.jpg\" width=\"1000\" height=\"486\" \/><\/a><\/p><p>5. Otro m\u00e9todo de descarga es hacer doble clic en la carpeta. Se descargar\u00e1 autom\u00e1ticamente un archivo con extensi\u00f3n .zip.<\/p><p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/FET-A.b.5.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/FET-A.b.5.jpg\" width=\"1000\" height=\"486\" \/><\/a><\/p><p>6. Al abrir el archivo .zip, se desplegar\u00e1n en archivos XML todos los CFDi extra\u00eddos del periodo consultado en el SAT.<\/p><p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/FET-A.b.6.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/FET-A.b.6.jpg\" width=\"1000\" height=\"487\" \/><\/a><\/p><p>7. Cuando abra uno de los archivos, puede ver lo que contiene el XML descargado.<\/p><p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/FET-A.b.7.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/FET-A.b.7.jpg\" width=\"1000\" height=\"535\" \/><\/a><\/p><p>Puede consultar las facturas extra\u00eddas con su solicitud en Axosnet Reporting mediante la fecha de validaci\u00f3n en la que se realiz\u00f3 la solicitud.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Una vez ejecutado un trabajo, localizar\u00e1 y extraer\u00e1 la informaci\u00f3n especificada en el momento de su programaci\u00f3n y la depositar\u00e1 en un Bucket que podr\u00e1 consultar de la siguiente forma: 1. Inicie sesi\u00f3n en la plataforma Axosnet Cloud Solutions\u00ae e ingrese a la aplicaci\u00f3n Axosnet Reporting V2.0. Nota: Si necesita m\u00e1s informaci\u00f3n, consulte el Manual [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":"","footnotes":""},"doc_category":[201],"doc_tag":[],"knowledge_base":[156],"class_list":["post-9571","docs","type-docs","status-publish","hentry","doc_category-es-af-manual","knowledge_base-es-fetcher"],"year_month":"2026-05","word_count":227,"total_views":"68","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"","author_nicename":"","author_url":"https:\/\/axosnet.info\/es\/author\/"},"doc_category_info":[{"term_name":"Manual de Usuario","term_url":"https:\/\/axosnet.info\/es\/docs\/es-fetcher\/es-af-manual\/"}],"doc_tag_info":[],"knowledge_base_info":[{"term_name":"Axosnet Fetcher","term_url":"https:\/\/axosnet.info\/es\/docs\/es-fetcher\/","term_slug":"es-fetcher"}],"knowledge_base_slug":["es-fetcher"],"_links":{"self":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/9571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/comments?post=9571"}],"version-history":[{"count":25,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/9571\/revisions"}],"predecessor-version":[{"id":38293,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/9571\/revisions\/38293"}],"wp:attachment":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/media?parent=9571"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/doc_category?post=9571"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/doc_tag?post=9571"},{"taxonomy":"knowledge_base","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/knowledge_base?post=9571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}