{"id":9486,"date":"2023-01-25T00:21:16","date_gmt":"2023-01-25T00:21:16","guid":{"rendered":"https:\/\/rfiii.com\/?post_type=docs&#038;p=9486"},"modified":"2023-08-05T00:47:24","modified_gmt":"2023-08-05T00:47:24","password":"","slug":"enviar-un-informe-para-su-aprobacion","status":"publish","type":"docs","link":"https:\/\/axosnet.info\/es\/docs\/enviar-un-informe-para-su-aprobacion\/","title":{"rendered":"Enviar un reporte para su aprobaci\u00f3n"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"9486\" class=\"elementor elementor-9486 elementor-5556\" data-elementor-post-type=\"docs\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1ceac1ce elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1ceac1ce\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4356b20\" data-id=\"4356b20\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f02f079 elementor-widget elementor-widget-text-editor\" data-id=\"7f02f079\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un usuario de viajes hace un reporte buscando la aceptaci\u00f3n de un aprobador de gastos. Esta secci\u00f3n explica c\u00f3mo enviar un reporte de gastos de SAP Concur a AxosMoney para que est\u00e9 disponible para su revisi\u00f3n y autorizaci\u00f3n.<\/p>\n<p>El proceso de env\u00edo sigue los siguientes pasos.<\/p>\n<p>1. Inicie sesi\u00f3n en su SAP Concur y luego, en la secci\u00f3n &#8220;Informes abiertos&#8221;, haga clic en un informe.<\/p>\n<p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/AXM-D.c.1.png\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/AXM-D.c.1.png\" width=\"1891\" height=\"913\"><\/a><\/p>\n<p>2. Haga clic en el bot\u00f3n &#8220;Agregar gasto&#8221; en la pesta\u00f1a &#8220;Gastos&#8221;.<\/p>\n<p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/AXM-D.c.2.png\"><img decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/AXM-D.c.2.png\" width=\"1890\" height=\"911\"><\/a><\/p>\n<p>3. Haga clic en la pesta\u00f1a &#8220;Crear un gasto nuevo&#8221; y seleccione un tipo de gasto de la lista.<\/p>\n<p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/AXM-D.c.3.png\"><img decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/AXM-D.c.3.png\" width=\"1892\" height=\"905\"><\/a><\/p>\n<p>4. Rellene los campos obligatorios (los marcados con asteriscos).<\/p>\n<p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/AXM-D.c.4.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/AXM-D.c.4.png\" width=\"1893\" height=\"913\"><\/a><\/p>\n<p>5. Haga clic en el bot\u00f3n &#8220;Guardar gasto&#8221;.<\/p>\n<p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/AXM-D.c.5.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/AXM-D.c.5.png\" width=\"1670\" height=\"912\"><\/a><\/p>\n<p>6. Marque la casilla de verificaci\u00f3n en el lado izquierdo del gasto y haga clic en el bot\u00f3n &#8220;Enviar informe&#8221;.<\/p>\n<p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/AXM-D.c.6.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/AXM-D.c.6.png\" width=\"1692\" height=\"916\"><\/a><\/p>\n<p>7. Aparecer\u00e1 una ventana. Le mostrar\u00e1 un resumen del reporte antes de enviarlo al aprobador. Si todo est\u00e1 bien, haga clic en el bot\u00f3n &#8220;Enviar informe&#8221;.<\/p>\n<p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/AXM-D.c.7.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/AXM-D.c.7.png\" width=\"1828\" height=\"911\"><\/a><\/p>\n<p>8. Si el reporte de gastos incluye recibos, aseg\u00farese de que todos hayan cargado los documentos originales cuando los env\u00ede. De lo contrario, Concur requerir\u00e1 que lo hagas como se muestra en la siguiente imagen.<\/p>\n<p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/AXM-D.c.8.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/AXM-D.c.8.png\" width=\"1831\" height=\"909\"><\/a><\/p>\n<p>9. Aparecer\u00e1 otra ventana inform\u00e1ndole que el informe se ha enviado con \u00e9xito, luego haga clic en &#8220;Cerrar&#8221;.<\/p>\n<p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/AXM-D.c.9.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/AXM-D.c.9.png\" width=\"1742\" height=\"912\"><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Un usuario de viajes hace un reporte buscando la aceptaci\u00f3n de un aprobador de gastos. Esta secci\u00f3n explica c\u00f3mo enviar un reporte de gastos de SAP Concur a AxosMoney para que est\u00e9 disponible para su revisi\u00f3n y autorizaci\u00f3n. El proceso de env\u00edo sigue los siguientes pasos. 1. Inicie sesi\u00f3n en su SAP Concur y luego, [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":"","footnotes":""},"doc_category":[181],"doc_tag":[],"knowledge_base":[154],"class_list":["post-9486","docs","type-docs","status-publish","hentry","doc_category-es-amon-w-inform","knowledge_base-es-axosmoney-web"],"year_month":"2026-07","word_count":221,"total_views":"169","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"","author_nicename":"","author_url":"https:\/\/axosnet.info\/es\/author\/"},"doc_category_info":[{"term_name":"Reportes AxosMoney Web","term_url":"https:\/\/axosnet.info\/es\/docs\/es-axosmoney-web\/es-amon-w-inform\/"}],"doc_tag_info":[],"knowledge_base_info":[{"term_name":"AxosMoney - Web","term_url":"https:\/\/axosnet.info\/es\/docs\/es-axosmoney-web\/","term_slug":"es-axosmoney-web"}],"knowledge_base_slug":["es-axosmoney-web"],"_links":{"self":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/9486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/comments?post=9486"}],"version-history":[{"count":22,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/9486\/revisions"}],"predecessor-version":[{"id":11929,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/9486\/revisions\/11929"}],"wp:attachment":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/media?parent=9486"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/doc_category?post=9486"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/doc_tag?post=9486"},{"taxonomy":"knowledge_base","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/knowledge_base?post=9486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}