{"id":9402,"date":"2023-01-23T16:54:20","date_gmt":"2023-01-23T16:54:20","guid":{"rendered":"https:\/\/rfiii.com\/?post_type=docs&#038;p=9402"},"modified":"2024-10-26T18:09:10","modified_gmt":"2024-10-26T18:09:10","password":"","slug":"asigne-el-permiso-puede-preparar","status":"publish","type":"docs","link":"https:\/\/axosnet.info\/es\/docs\/asigne-el-permiso-puede-preparar\/","title":{"rendered":"Asigne el permiso &#8220;Puede preparar&#8221;"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"9402\" class=\"elementor elementor-9402 elementor-5393\" data-elementor-post-type=\"docs\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-99addf3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"99addf3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8ab84d0\" data-id=\"8ab84d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ad399dc elementor-widget elementor-widget-text-editor\" data-id=\"3ad399dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cuando un usuario-1 (axmexp_caap) necesita asignar el permiso &#8220;Puede preparar&#8221; a un usuario-2 (axmexp_cbu) es porque este \u00faltimo podr\u00e1 crear y editar un reporte en su nombre.<\/p><p>Para asignar los permisos, el usuario-1 debe seguir los pasos a continuaci\u00f3n.<\/p><p>1. Marque la casilla &#8220;Puede preparar&#8221;.<\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2024\/10\/AXM.B.02-SPA-01.png\" \/><\/p><p><strong>Nota<\/strong>: cuando marca la casilla &#8220;Puede preparar&#8221;, la casilla &#8220;Puede ver comprobantes&#8221; se marcar\u00e1 autom\u00e1ticamente al mismo tiempo.<\/p><p>\u00a0<\/p><p>Esta configuraci\u00f3n permite que el usuario-2 cree reportes en nombre del usuario-1 utilizando los gastos registrados en la cuenta del usuario-1.<\/p><p>2. El siguiente paso es activar la funci\u00f3n &#8220;Actuar como&#8221; en la aplicaci\u00f3n AxosMoney, ir a la esquina superior izquierda, hacer clic en la lista desplegable de usuarios (que le delegaron permisos) y seleccionar uno.<\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2024\/10\/AXM.B.02-SPA-02.png\" \/><\/p><p>\u00a0<\/p><p>3. Tenga en cuenta que la lista de gastos y reportes cambia. AxosMoney le mostrar\u00e1 los reportes y gastos del usuario seleccionado.<\/p><p>El usuario-2 puede confirmar que est\u00e1 actuando como el usuario-1 observando el men\u00fa en el lado izquierdo de la p\u00e1gina, hay un \u00e1rea verde con el texto &#8220;Actuando como&#8221; y el nombre del usuario-1.<\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2024\/10\/AXM.B.02-SPA-03.png\" \/><\/p><p>4. A partir de este momento, AxosMoney permitir\u00e1 que el usuario-2 cree reportes en nombre del usuario-1.<\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2024\/10\/AXM.B.02-SPA-04.png\" \/><\/p><p>5. Cuando al usuario-2 se le asignan los permisos &#8220;Puede preparar&#8221;, solo ve dos pesta\u00f1as en la p\u00e1gina &#8220;Reportes&#8221;: &#8220;No enviados&#8221; y &#8220;Pendiente Aprobaci\u00f3n&#8221;.<\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2024\/10\/AXM.B.02-SPA-05.png\" \/><\/p><p><strong>Nota<\/strong>: la secci\u00f3n &#8220;Para aprobar&#8221; no est\u00e1 visible cuando el usuario solo tiene los permisos &#8220;Puede preparar&#8221;<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Cuando un usuario-1 (axmexp_caap) necesita asignar el permiso &#8220;Puede preparar&#8221; a un usuario-2 (axmexp_cbu) es porque este \u00faltimo podr\u00e1 crear y editar un reporte en su nombre. Para asignar los permisos, el usuario-1 debe seguir los pasos a continuaci\u00f3n. 1. Marque la casilla &#8220;Puede preparar&#8221;. Nota: cuando marca la casilla &#8220;Puede preparar&#8221;, la casilla &#8220;Puede [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":"","footnotes":""},"doc_category":[179],"doc_tag":[],"knowledge_base":[154],"class_list":["post-9402","docs","type-docs","status-publish","hentry","doc_category-es-amon-w-actu","knowledge_base-es-axosmoney-web"],"year_month":"2026-07","word_count":240,"total_views":"162","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"","author_nicename":"","author_url":"https:\/\/axosnet.info\/es\/author\/"},"doc_category_info":[{"term_name":"Actuando como","term_url":"https:\/\/axosnet.info\/es\/docs\/es-axosmoney-web\/es-amon-w-actu\/"}],"doc_tag_info":[],"knowledge_base_info":[{"term_name":"AxosMoney - Web","term_url":"https:\/\/axosnet.info\/es\/docs\/es-axosmoney-web\/","term_slug":"es-axosmoney-web"}],"knowledge_base_slug":["es-axosmoney-web"],"_links":{"self":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/9402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/comments?post=9402"}],"version-history":[{"count":16,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/9402\/revisions"}],"predecessor-version":[{"id":25579,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/9402\/revisions\/25579"}],"wp:attachment":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/media?parent=9402"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/doc_category?post=9402"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/doc_tag?post=9402"},{"taxonomy":"knowledge_base","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/knowledge_base?post=9402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}