{"id":9367,"date":"2023-01-23T05:42:56","date_gmt":"2023-01-23T05:42:56","guid":{"rendered":"https:\/\/rfiii.com\/?post_type=docs&#038;p=9367"},"modified":"2025-06-17T23:37:53","modified_gmt":"2025-06-17T23:37:53","password":"","slug":"instalacion-de-axosmoney-desde-app-center","status":"publish","type":"docs","link":"https:\/\/axosnet.info\/es\/docs\/instalacion-de-axosmoney-desde-app-center\/","title":{"rendered":"Instalaci\u00f3n de AxosMoney desde el Centro de Aplicaciones"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"9367\" class=\"elementor elementor-9367 elementor-5362\" data-elementor-post-type=\"docs\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a5899aa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3a5899aa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3feb9252\" data-id=\"3feb9252\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-57ab40a8 elementor-widget elementor-widget-text-editor\" data-id=\"57ab40a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cuando un nuevo cliente quiera instalar la aplicaci\u00f3n AxosMoney, deber\u00e1 seguir los siguientes pasos:<\/p><p>1. En la p\u00e1gina de inicio de SAP Concur, haga clic en &#8220;Centro de aplicaciones&#8221;.<\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/06\/AXM-QC-Instalar_01.png\" \/><\/p><p>2. Escriba &#8220;AxosMoney&#8221; en el cuadro de b\u00fasqueda que se encuentra en la parte superior derecha de la p\u00e1gina. Haga clic en &#8220;Buscar&#8221;.<\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/06\/AXM-QC-Instalar_02.png\" \/><\/p><p>3. Se mostrar\u00e1 la soluci\u00f3n AxosMoney. Haga clic en AxosMoney.<\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/06\/AXM-QC-Instalar_03.png\" \/><\/p><p>4. Ser\u00e1 redirigido a la p\u00e1gina de la aplicaci\u00f3n AxosMoney. A continuaci\u00f3n, haga clic en el enlace &#8220;Informaci\u00f3n de solicitudes&#8221; debajo del bot\u00f3n &#8220;Conectar&#8221;.<\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/06\/AXM-QC-Instalar_04.png\" \/><\/p><p>5. Ser\u00e1 redirigido a un formulario de SAP Concur. Para solicitar una demostraci\u00f3n, complete el formulario y env\u00edelo. El \u00e1rea comercial se comunicar\u00e1 con usted a la brevedad.<\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/06\/AXM-QC-Instalar_05.png\" \/><\/p><p>Una vez que haya instalado la aplicaci\u00f3n AxosMoney, puede realizar el proceso de conexi\u00f3n r\u00e1pida, que se revisa en las siguientes secciones.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Cuando un nuevo cliente quiera instalar la aplicaci\u00f3n AxosMoney, deber\u00e1 seguir los siguientes pasos: 1. En la p\u00e1gina de inicio de SAP Concur, haga clic en &#8220;Centro de aplicaciones&#8221;. 2. Escriba &#8220;AxosMoney&#8221; en el cuadro de b\u00fasqueda que se encuentra en la parte superior derecha de la p\u00e1gina. Haga clic en &#8220;Buscar&#8221;. 3. Se mostrar\u00e1 [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":"","footnotes":""},"doc_category":[178],"doc_tag":[],"knowledge_base":[154],"class_list":["post-9367","docs","type-docs","status-publish","hentry","doc_category-es-amon-w-emp","knowledge_base-es-axosmoney-web"],"year_month":"2026-05","word_count":146,"total_views":"118","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"","author_nicename":"","author_url":"https:\/\/axosnet.info\/es\/author\/"},"doc_category_info":[{"term_name":"Comenzando AxosMoney Web","term_url":"https:\/\/axosnet.info\/es\/docs\/es-axosmoney-web\/es-amon-w-emp\/"}],"doc_tag_info":[],"knowledge_base_info":[{"term_name":"AxosMoney - Web","term_url":"https:\/\/axosnet.info\/es\/docs\/es-axosmoney-web\/","term_slug":"es-axosmoney-web"}],"knowledge_base_slug":["es-axosmoney-web"],"_links":{"self":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/9367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/comments?post=9367"}],"version-history":[{"count":23,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/9367\/revisions"}],"predecessor-version":[{"id":34421,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/9367\/revisions\/34421"}],"wp:attachment":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/media?parent=9367"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/doc_category?post=9367"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/doc_tag?post=9367"},{"taxonomy":"knowledge_base","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/knowledge_base?post=9367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}