{"id":8860,"date":"2023-02-04T00:41:10","date_gmt":"2023-02-04T00:41:10","guid":{"rendered":"https:\/\/rfiii.com\/docs\/carga-de-una-sola-factura\/"},"modified":"2023-08-14T17:38:11","modified_gmt":"2023-08-14T17:38:11","password":"","slug":"carga-de-una-sola-factura","status":"publish","type":"docs","link":"https:\/\/axosnet.info\/es\/docs\/carga-de-una-sola-factura\/","title":{"rendered":"Carga de una sola factura"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"8860\" class=\"elementor elementor-8860 elementor-6376\" data-elementor-post-type=\"docs\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-33aed30e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"33aed30e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3f2b88fc\" data-id=\"3f2b88fc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29b4f372 elementor-widget elementor-widget-text-editor\" data-id=\"29b4f372\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Para validar una sola factura, siga estos pasos:<\/p><p>1. Inicie sesi\u00f3n en la plataforma de Axosnet Cloud Solutions\u00ae en <a href=\"https:\/\/acs.axosnet.com\/\" target=\"_new\">https:\/\/acs.axosnet.com<\/a><\/p><p><b>Nota<\/b>: Si necesita m\u00e1s informaci\u00f3n, consulte el Manual de ACS, secci\u00f3n de inicio de sesi\u00f3n.<\/p><p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/AXM-A.1.png\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/AXM-A.1.png\" width=\"1365\" height=\"656\" \/><\/a><\/p><p>2.Una vez que se haya registrado en el portal de proveedores, debe ingresar a la secci\u00f3n &#8220;Ingreso de Facturas&#8221;.<\/p><p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/ACP-B.A.2.png\"><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/ACP-B.A.2.png\" width=\"1891\" height=\"861\" \/><\/a><\/p><p>3. Haga clic en &#8220;Seleccionar archivo&#8221; en el campo &#8220;CFDi(s) XMLs&#8221;.<\/p><p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/ACP-B.A.3.png\"><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/ACP-B.A.3.png\" width=\"1893\" height=\"865\" \/><\/a><\/p><p>4. Aparecer\u00e1 una ventana del explorador de archivos, seleccione el archivo XML de su factura.<\/p><p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/ACP-B.A.4.png\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/ACP-B.A.4.png\" width=\"1895\" height=\"863\" \/><\/a><\/p><p>5. Haga clic en &#8220;Seleccionar archivo&#8221; en el campo &#8220;PDF(s):&#8221;.<\/p><p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/ACP-B.A.5.png\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/ACP-B.A.5.png\" width=\"1895\" height=\"867\" \/><\/a><\/p><p>6. Aparecer\u00e1 una ventana del explorador de archivos, seleccione el archivo PDF de su factura.<\/p><p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/ACP-B.A.6.png\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/ACP-B.A.6.png\" width=\"1893\" height=\"860\" \/><\/a><\/p><p>7. Haga clic en &#8220;Cargar&#8221; y espere a que el sistema realice las operaciones correspondientes.<\/p><p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/ACP-B.A.7.png\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/ACP-B.A.7.png\" width=\"1892\" height=\"864\" \/><\/a><\/p><p>8. El sistema realizar\u00e1 la validaci\u00f3n fiscal:<\/p><ul><li>Estructura: Que el CFDi cumpla con las directrices del anexo 20 del SAT.<\/li><li>Fiscal: Que el certificado y el sello de la factura sean v\u00e1lidos.<\/li><li>Monto: Que la suma del subtotal de los conceptos sea igual al subtotal de la factura.<\/li><li>Vigencia: Que la factura sea v\u00e1lida ante el SAT.<\/li><\/ul><p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/ACP-B.A.8.png\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/ACP-B.A.8.png\" width=\"1894\" height=\"868\" \/><\/a><\/p><p>9. Al hacer clic en el icono de la lupa en la columna &#8220;Detalle&#8221;, podr\u00e1 consultar los detalles de cualquier factura validada.<\/p><p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/ACP-B.A.9.png\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/ACP-B.A.9.png\" width=\"1892\" height=\"859\" \/><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Para validar una sola factura, siga estos pasos: 1. Inicie sesi\u00f3n en la plataforma de Axosnet Cloud Solutions\u00ae en https:\/\/acs.axosnet.com Nota: Si necesita m\u00e1s informaci\u00f3n, consulte el Manual de ACS, secci\u00f3n de inicio de sesi\u00f3n. 2.Una vez que se haya registrado en el portal de proveedores, debe ingresar a la secci\u00f3n &#8220;Ingreso de Facturas&#8221;. 3. [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":"","footnotes":""},"doc_category":[144],"doc_tag":[],"knowledge_base":[145],"class_list":["post-8860","docs","type-docs","status-publish","hentry","doc_category-es-acp-proceso-de-validacion","knowledge_base-es-nube-de-axosnet"],"year_month":"2026-07","word_count":203,"total_views":"213","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"","author_nicename":"","author_url":"https:\/\/axosnet.info\/es\/author\/"},"doc_category_info":[{"term_name":"Proceso de Validaci\u00f3n","term_url":"https:\/\/axosnet.info\/es\/docs\/es-nube-de-axosnet\/es-acp-proceso-de-validacion\/"}],"doc_tag_info":[],"knowledge_base_info":[{"term_name":"Axosnet Cloud Portal 1.0","term_url":"https:\/\/axosnet.info\/es\/docs\/es-nube-de-axosnet\/","term_slug":"es-nube-de-axosnet"}],"knowledge_base_slug":["es-nube-de-axosnet"],"_links":{"self":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/8860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/comments?post=8860"}],"version-history":[{"count":21,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/8860\/revisions"}],"predecessor-version":[{"id":12853,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/8860\/revisions\/12853"}],"wp:attachment":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/media?parent=8860"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/doc_category?post=8860"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/doc_tag?post=8860"},{"taxonomy":"knowledge_base","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/knowledge_base?post=8860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}