{"id":41076,"date":"2026-03-13T00:00:42","date_gmt":"2026-03-13T00:00:42","guid":{"rendered":"https:\/\/axosnet.info\/?post_type=docs&#038;p=41076"},"modified":"2026-06-08T21:46:10","modified_gmt":"2026-06-08T21:46:10","password":"","slug":"avisos-de-liberacion-2026","status":"publish","type":"docs","link":"https:\/\/axosnet.info\/es\/docs\/avisos-de-liberacion-2026\/","title":{"rendered":"Avisos de Liberaci\u00f3n 2026"},"content":{"rendered":"\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/axosnet.info\/wp-content\/uploads\/2026\/06\/AvisoActualizacion_ACS-Administracion-Documentos_V1.0_ESP.pdf\" type=\"application\/pdf\" style=\"width:100%;height:270px\" aria-label=\"Incrustado de AvisoActualizacion_ACS-Administracion-Documentos_V1.0_ESP.\"><\/object><a id=\"wp-block-file--media-bed3b38c-97ff-4a1f-8929-58430cdabdd9\" href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2026\/06\/AvisoActualizacion_ACS-Administracion-Documentos_V1.0_ESP.pdf\">AvisoActualizacion_ACS-Administracion-Documentos_V1.0_ESP<\/a><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\">Aviso de Liberaci\u00f3n ACS: Administraci\u00f3n de Documentos<\/h2>\n\n\n\n<p class=\"\">15 de Junio del 2026<\/p>\n\n\n\n<p class=\"\">Se trata de una soluci\u00f3n integrada en <strong>Axosnet Cloud Solutions<\/strong> dise\u00f1ada para centralizar el almacenamiento, la organizaci\u00f3n y el intercambio de archivos corporativos. Esta herramienta agiliza la interacci\u00f3n con proveedores al permitir requerir y recibir documentos directamente en el sistema, habilitando una validaci\u00f3n inmediata por parte del cliente mediante procesos de aprobaci\u00f3n o rechazo.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/axosnet.info\/wp-content\/uploads\/2026\/05\/AvisoActualizacion_ACP-Notificacion-Cumplimiento-REP_V1.0_ESP.pdf\" type=\"application\/pdf\" style=\"width:100%;height:310px\" aria-label=\"Incrustado de AvisoActualizacion_ACP-Notificacion-Cumplimiento-REP_V1.0_ESP.\"><\/object><a id=\"wp-block-file--media-4f1341fc-1aca-4e01-af62-dcb9b36e86eb\" href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2026\/05\/AvisoActualizacion_ACP-Notificacion-Cumplimiento-REP_V1.0_ESP.pdf\">AvisoActualizacion_ACP-Notificacion-Cumplimiento-REP_V1.0_ESP<\/a><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\">Aviso de Liberaci\u00f3n ACP: Notificaci\u00f3n y Cumplimiento de Complemento de Pago<\/h2>\n\n\n\n<p class=\"\">21 de Mayo del 2026<\/p>\n\n\n\n<p class=\"\">El Complemento de Recepci\u00f3n de Pago (REP) es un comprobante fiscal indispensable en M\u00e9xico para formalizar el cobro o pago de facturas de Pago en Parcialidades o Diferido (PPD). Axosnet Cloud Portal integra dos funcionalidades clave para asegurar el cumplimiento.<\/p>\n\n\n\n<p class=\"\"><strong>Notificaciones por REP<\/strong>: Env\u00edo automatizado de alertas por email y recordatorios estrat\u00e9gicos para cumplir estrictamente con los plazos legales de de emisi\u00f3n del REP tras recibir un pago. <\/p>\n\n\n\n<p class=\"\"><strong>Cumplimiento de REP<\/strong>: Control preventivo que impide a proveedores con REP pendientes la carga de nuevas facturas, garantizando orden administrativo y fiscal.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/axosnet.info\/wp-content\/uploads\/2026\/04\/AvisoActualizacion_AXM-ImportarUsuarios_V1.0_ESP.pdf\" type=\"application\/pdf\" style=\"width:100%;height:330px\" aria-label=\"Incrustado de AvisoActualizacion_AXM-ImportarUsuarios_V1.0_ESP.\"><\/object><a id=\"wp-block-file--media-dec8fd0d-728a-4bde-973a-9a9310d61247\" href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2026\/04\/AvisoActualizacion_AXM-ImportarUsuarios_V1.0_ESP.pdf\">AvisoActualizacion_AXM-ImportarUsuarios_V1.0_ESP<\/a><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\">Aviso de Liberaci\u00f3n Axosmoney: Importar usuarios desde SAP Concur<\/h2>\n\n\n\n<p class=\"\">04 de Mayo del 2026<\/p>\n\n\n\n<p class=\"\">La funcionalidad de Importar Usuarios permite conectar la plataforma de Axosnet Cloud Solutions (ACS) con sistemas de terceros, como SAP Concur, para la importaci\u00f3n de perfiles de usuario. Esta conexi\u00f3n requiere la configuraci\u00f3n de las credenciales de los terceros correspondientes (Client ID, Secret client, Token, etc.).<\/p>\n\n\n\n<p class=\"\">En un avance estrat\u00e9gico para los suscriptores activos de Axosmoney Expense,<strong> la importaci\u00f3n de usuarios ahora utiliza la vinculaci\u00f3n QuickConnect existente con SAP Concur.<\/strong> Este desarrollo simplifica la sincronizaci\u00f3n de perfiles en el ecosistema Axosnet Cloud Solutions, aprovechando la conexi\u00f3n establecida y eliminando la necesidad de configurar credenciales de terceros<\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/axosnet.info\/wp-content\/uploads\/2026\/04\/AvisoActualizacion_AXM-Rewards-Amazon_V1.0_ESP.pdf\" type=\"application\/pdf\" style=\"width:100%;height:330px\" aria-label=\"Incrustado de AvisoActualizacion_AXM-Rewards-Amazon_V1.0_ESP.\"><\/object><a id=\"wp-block-file--media-e828b913-d269-4469-8983-90d16efaa7b6\" href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2026\/04\/AvisoActualizacion_AXM-Rewards-Amazon_V1.0_ESP.pdf\">AvisoActualizacion_AXM-Rewards-Amazon_V1.0_ESP<\/a><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\">Aviso de Liberaci\u00f3n Axosmoney: Rewards Integraci\u00f3n con Amazon Business<\/h2>\n\n\n\n<p class=\"\">27 de Abril del 2026<\/p>\n\n\n\n<p class=\"\">Es un sistema de reconocimiento y canjeo de puntos para empleados, que busca premiar el desempe\u00f1o, comportamiento o antig\u00fcedad, fomentando la motivaci\u00f3n, la lealtad y la cultura corporativa. <strong>Axosmoney Rewards se ha integrado con Amazon Business.<\/strong> Esta actualizaci\u00f3n ampl\u00eda significativamente el cat\u00e1logo de recompensas y beneficios, permitiendo a los colaboradores canjear sus puntos por productos disponibles en Amazon.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-stretch is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-file\"><object class=\"wp-block-file__embed\" data=\"https:\/\/axosnet.info\/wp-content\/uploads\/2026\/04\/AvisoActualizacion_ACS-Desactivar-MFA_V1.0_ESP.pdf\" type=\"application\/pdf\" style=\"width:100%;height:230px\" aria-label=\"AvisoActualizaci\u00f3n_ACS-Desactivar MFA_V1.0_ESP\"><\/object><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\">Aviso de Liberaci\u00f3n ACS: Desactivar MFA<\/h2>\n\n\n\n<p class=\"\">17 de Abril del 2026<\/p>\n\n\n\n<p class=\"\">Es una funcionalidad integrada en la plataforma ACS Management que permite al usuario con perfil de Administrador desactivar la Autenticaci\u00f3n Multifactor (MFA) de manera aut\u00f3noma para los usuarios de su organizaci\u00f3n.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/axosnet.info\/wp-content\/uploads\/2026\/03\/AvisoActualizacion_ACP_V1.0_ESP_20260309.pdf\" type=\"application\/pdf\" style=\"width:100%;height:270px\" aria-label=\"Incrustado de AvisoActualizaci\u00f3n_ACP_V1.0_ESP_20260309.\"><\/object><a id=\"wp-block-file--media-8684c864-5764-41e1-bc24-e5fa0bf61222\" href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2026\/03\/AvisoActualizacion_ACP_V1.0_ESP_20260309.pdf\">AvisoActualizaci\u00f3n_ACP_V1.0_ESP_20260309<\/a><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2026\/03\/AvisoActualizacion_ACP_V1.0_ESP_20260309.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-8684c864-5764-41e1-bc24-e5fa0bf61222\">Descarga<\/a><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\">Aviso de Liberaci\u00f3n ACP: Integraci\u00f3n con SAP Concur Invoice<\/h2>\n\n\n\n<p class=\"\">09 de Marzo del 2026<\/p>\n\n\n\n<p class=\"\">Es una potente integraci\u00f3n entre Axosnet Cloud Portal (ACP) y SAP Concur para brindarte un ecosistema financiero sincronizado, seguro y sin fricciones. Con esta funcionalidad, le das el control a tus proveedores mientras t\u00fa reduces errores y optimizas tu operaci\u00f3n al m\u00e1ximo.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/axosnet.info\/wp-content\/uploads\/2026\/03\/AvisoActualizacion_AXM_V1.0_ESP_20260309.pdf\" type=\"application\/pdf\" style=\"width:100%;height:240px\" aria-label=\"Incrustado de AvisoActualizaci\u00f3n_AXM_V1.0_ESP_20260309.\"><\/object><a id=\"wp-block-file--media-f033eb11-92b4-46dd-bbdc-bda883052550\" href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2026\/03\/AvisoActualizacion_AXM_V1.0_ESP_20260309.pdf\">AvisoActualizaci\u00f3n_AXM_V1.0_ESP_20260309<\/a><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2026\/03\/AvisoActualizacion_AXM_V1.0_ESP_20260309.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-f033eb11-92b4-46dd-bbdc-bda883052550\">Descarga<\/a><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\">Aviso de Liberaci\u00f3n AxosMoney: Validaci\u00f3n de Retenci\u00f3n<\/h2>\n\n\n\n<p class=\"\">09 de Marzo del 2026<\/p>\n\n\n\n<p class=\"\"><strong>Validaci\u00f3n de Retenciones en CFDI: <\/strong>Es un par\u00e1metro de configuraci\u00f3n que permite a los administradores de AxosMoney definir c\u00f3mo deben tratarse las facturas que incluyan IVA en el nodo de Retenciones del CFDI, dentro del proceso de gesti\u00f3n de gastos.<br><\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Aviso de Liberaci\u00f3n ACS: Administraci\u00f3n de Documentos 15 de Junio del 2026 Se trata de una soluci\u00f3n integrada en Axosnet Cloud Solutions dise\u00f1ada para centralizar el almacenamiento, la organizaci\u00f3n y el intercambio de archivos corporativos. Esta herramienta agiliza la interacci\u00f3n con proveedores al permitir requerir y recibir documentos directamente en el sistema, habilitando una validaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":"","footnotes":""},"doc_category":[250],"doc_tag":[],"knowledge_base":[147],"class_list":["post-41076","docs","type-docs","status-publish","hentry","doc_category-avisos-de-liberacion","knowledge_base-es-notas"],"year_month":"2026-07","word_count":567,"total_views":0,"reactions":{"happy":0,"normal":0,"sad":0},"author_info":{"name":"Maria Morales","author_nicename":"mmorales","author_url":"https:\/\/axosnet.info\/es\/author\/mmorales\/"},"doc_category_info":[{"term_name":"Avisos de Liberaci\u00f3n","term_url":"https:\/\/axosnet.info\/es\/docs\/es-notas\/avisos-de-liberacion\/"}],"doc_tag_info":[],"knowledge_base_info":[{"term_name":"Notas Recientes","term_url":"https:\/\/axosnet.info\/es\/docs\/es-notas\/","term_slug":"es-notas"}],"knowledge_base_slug":["es-notas"],"_links":{"self":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/41076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/comments?post=41076"}],"version-history":[{"count":15,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/41076\/revisions"}],"predecessor-version":[{"id":42469,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/41076\/revisions\/42469"}],"wp:attachment":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/media?parent=41076"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/doc_category?post=41076"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/doc_tag?post=41076"},{"taxonomy":"knowledge_base","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/knowledge_base?post=41076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}