{"id":40837,"date":"2026-03-02T18:41:54","date_gmt":"2026-03-02T18:41:54","guid":{"rendered":"https:\/\/axosnet.info\/?post_type=docs&#038;p=40837"},"modified":"2026-03-02T17:40:48","modified_gmt":"2026-03-02T17:40:48","password":"","slug":"ingreso-de-facturas-xml-y-pdf-con-orden-de-compra","status":"publish","type":"docs","link":"https:\/\/axosnet.info\/es\/docs\/ingreso-de-facturas-xml-y-pdf-con-orden-de-compra\/","title":{"rendered":"Ingreso de Facturas XML y PDF con \u00d3rden de Compra"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"40837\" class=\"elementor elementor-40837 elementor-40920\" data-elementor-post-type=\"docs\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8429a74 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8429a74\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b70d538\" data-id=\"b70d538\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b4957c0 elementor-widget elementor-widget-text-editor\" data-id=\"b4957c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">La funcionalidad dentro de Axosnet Cloud Portal (ACP) 3.0, espec\u00edficamente dise\u00f1ada para el m\u00f3dulo de Concur Invoice, ofrece una herramienta esencial para la gesti\u00f3n y conciliaci\u00f3n eficiente de documentos.<\/span><\/p><p><span style=\"font-weight: 400;\">Esta caracter\u00edstica permite a los usuarios <\/span><b>relacionar de manera precisa y directa facturas electr\u00f3nicas recibidas con las \u00d3rdenes de Compra (OC)<\/b><span style=\"font-weight: 400;\"> que previamente han sido generadas y aprobadas dentro del sistema Concur Invoice. Siga estos pasos:<\/span><\/p><p><span style=\"font-weight: 400;\">1. Despu\u00e9s de crear la orden de compra en Concur, acceda a la secci\u00f3n <\/span><b>Facturas &gt; Ingreso de Facturas<\/b><span style=\"font-weight: 400;\"> en ACP para vincular la factura con la orden de compra de SAP Concur.<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2026\/03\/acp_concur_enviar-01.png\" \/><\/p><p><span style=\"font-weight: 400;\">2. Podr\u00e1 relacionar las facturas en ACP agregando el n\u00famero de compra proporcionado en SAP Concur. Haga clic en <\/span><b>Continuar.<\/b><\/p><p><b>Nota<\/b><span style=\"font-weight: 400;\">: A diferencia de ACP, que permite vincular una factura a m\u00faltiples \u00f3rdenes de compra, la integraci\u00f3n con Concur actualmente solo soporta una \u00fanica orden de compra por factura. En caso de ingresar varias, solo se considerar\u00e1 la \u00faltima orden a\u00f1adida.<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2026\/03\/acp_concur_enviar-02.png\" \/><\/p><p><span>3. Haga clic en <\/span><b>Procesar<\/b><span> para procesar la factura.<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2026\/03\/acp_concur_enviar-03.png\" \/><\/p><p>4. La factura se visualizar\u00e1 en SAP Concur una vez que haya concluido su procesamiento.<\/p><p><b>Nota:<\/b><span style=\"font-weight: 400;\"> Es posible ingresar facturas sin \u00d3rdenes de Compra.<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2026\/03\/acp_concur_enviar-04.png\" \/><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2026\/03\/acp_concur_enviar-05.png\" \/><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La funcionalidad dentro de Axosnet Cloud Portal (ACP) 3.0, espec\u00edficamente dise\u00f1ada para el m\u00f3dulo de Concur Invoice, ofrece una herramienta esencial para la gesti\u00f3n y conciliaci\u00f3n eficiente de documentos. Esta caracter\u00edstica permite a los usuarios relacionar de manera precisa y directa facturas electr\u00f3nicas recibidas con las \u00d3rdenes de Compra (OC) que previamente han sido generadas [&hellip;]<\/p>\n","protected":false},"author":36,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":"","footnotes":""},"doc_category":[554],"doc_tag":[],"knowledge_base":[440],"class_list":["post-40837","docs","type-docs","status-publish","hentry","doc_category-concur-invoice-es","knowledge_base-axosnet-cloud-portal-3-es"],"year_month":"2026-05","word_count":200,"total_views":0,"reactions":{"happy":0,"normal":0,"sad":0},"author_info":{"name":"Daniel Galindo","author_nicename":"dgalindo","author_url":"https:\/\/axosnet.info\/es\/author\/dgalindo\/"},"doc_category_info":[{"term_name":"Concur Invoice","term_url":"https:\/\/axosnet.info\/es\/docs\/axosnet-cloud-portal-3-es\/concur-invoice-es\/"}],"doc_tag_info":[],"knowledge_base_info":[{"term_name":"Axosnet Cloud Portal 3.0","term_url":"https:\/\/axosnet.info\/es\/docs\/axosnet-cloud-portal-3-es\/","term_slug":"axosnet-cloud-portal-3-es"}],"knowledge_base_slug":["axosnet-cloud-portal-3-es"],"_links":{"self":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/40837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/comments?post=40837"}],"version-history":[{"count":4,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/40837\/revisions"}],"predecessor-version":[{"id":40851,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/40837\/revisions\/40851"}],"wp:attachment":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/media?parent=40837"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/doc_category?post=40837"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/doc_tag?post=40837"},{"taxonomy":"knowledge_base","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/knowledge_base?post=40837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}