{"id":38382,"date":"2025-11-25T16:32:23","date_gmt":"2025-11-25T16:32:23","guid":{"rendered":"https:\/\/axosnet.info\/?post_type=docs&#038;p=38382"},"modified":"2026-06-10T17:47:18","modified_gmt":"2026-06-10T17:47:18","password":"","slug":"metodos-de-pago-2","status":"publish","type":"docs","link":"https:\/\/axosnet.info\/es\/docs\/metodos-de-pago-2\/","title":{"rendered":"M\u00e9todos de Pago"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"38382\" class=\"elementor elementor-38382 elementor-38484\" data-elementor-post-type=\"docs\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bbab458 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bbab458\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-534fecd\" data-id=\"534fecd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-afcaab5 elementor-widget elementor-widget-text-editor\" data-id=\"afcaab5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En esta secci\u00f3n, los administradores de la cuenta pueden agregar validaciones de m\u00e9todos de pago aceptados en su cuenta AxosMoney.<\/p><p>Para configurarlos, siga los siguientes pasos:<\/p><p>1. Ingrese a la secci\u00f3n <strong>Administraci\u00f3n<\/strong> en el men\u00fa lateral izquierdo y haga clic en <strong>Configuraci\u00f3n de AxosMoney<\/strong>.<\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2026\/06\/AXM-Codigos-00.png\" \/><\/p><p>2. Seleccione la pesta\u00f1a\u00a0<strong>Reglas de Validaci\u00f3n por Pa\u00eds.<\/strong><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2026\/06\/AXM-Codigos-01.png\" \/><\/p><p>3. Seleccione el Pa\u00eds que desea configurar.<\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2026\/06\/AXM-Codigos-03.png\" \/><\/p><p>4. Dirigase hac\u00eda abajo y localice la secci\u00f3n <strong>M\u00e9todos de Pago<\/strong>. Para agregar un c\u00f3digo asegurese que la funci\u00f3n est\u00e9 habilitada haciendo clic en el bot\u00f3n tipo switch.<\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2026\/06\/AXM-MetodosPago-04.png\" \/><\/p><p>5. Una vez activa la funcionalidad haga clic en <strong>Agregar C\u00f3digo.<\/strong><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2026\/06\/AXM-MetodosPago-05.png\" \/><\/p><p>6. Aparecer\u00e1 una ventana emergente, haga clic en la lista de c\u00f3digos con los M\u00e9todos de Pago y seleccione el correspondiente. Luego, haga clic en <strong>Agregar <\/strong>para a\u00f1adirlo a sus validaciones.<\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2026\/06\/AXM-MetodosPago-06.png\" \/><\/p><p>5. Aparecer\u00e1 un mensaje de confirmaci\u00f3n y el c\u00f3digo aparecer\u00e1 en la lista de validaciones a\u00f1adidas.<\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2026\/06\/AXM-MetodosPago-07.png\" \/><\/p><p>6. Si desea eliminar un c\u00f3digo de la tabla de validaci\u00f3n, presione el bot\u00f3n rojo con el bote de basura y se eliminar\u00e1 de las validaciones.<\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2026\/06\/AXM-MetodosPago-08.png\" \/><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2026\/06\/AXM-MetodosPago-09.png\" \/><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>En esta secci\u00f3n, los administradores de la cuenta pueden agregar validaciones de m\u00e9todos de pago aceptados en su cuenta AxosMoney. Para configurarlos, siga los siguientes pasos: 1. Ingrese a la secci\u00f3n Administraci\u00f3n en el men\u00fa lateral izquierdo y haga clic en Configuraci\u00f3n de AxosMoney. 2. Seleccione la pesta\u00f1a\u00a0Reglas de Validaci\u00f3n por Pa\u00eds. 3. Seleccione el [&hellip;]<\/p>\n","protected":false},"author":36,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":"","footnotes":""},"doc_category":[183],"doc_tag":[],"knowledge_base":[154],"class_list":["post-38382","docs","type-docs","status-publish","hentry","doc_category-es-amon-w-gest","knowledge_base-es-axosmoney-web"],"year_month":"2026-07","word_count":189,"total_views":0,"reactions":{"happy":0,"normal":0,"sad":0},"author_info":{"name":"Daniel Galindo","author_nicename":"dgalindo","author_url":"https:\/\/axosnet.info\/es\/author\/dgalindo\/"},"doc_category_info":[{"term_name":"Administraci\u00f3n","term_url":"https:\/\/axosnet.info\/es\/docs\/es-axosmoney-web\/es-amon-w-gest\/"}],"doc_tag_info":[],"knowledge_base_info":[{"term_name":"AxosMoney - Web","term_url":"https:\/\/axosnet.info\/es\/docs\/es-axosmoney-web\/","term_slug":"es-axosmoney-web"}],"knowledge_base_slug":["es-axosmoney-web"],"_links":{"self":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/38382","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/comments?post=38382"}],"version-history":[{"count":16,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/38382\/revisions"}],"predecessor-version":[{"id":42966,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/38382\/revisions\/42966"}],"wp:attachment":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/media?parent=38382"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/doc_category?post=38382"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/doc_tag?post=38382"},{"taxonomy":"knowledge_base","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/knowledge_base?post=38382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}