{"id":26956,"date":"2024-12-09T23:24:27","date_gmt":"2024-12-09T23:24:27","guid":{"rendered":"https:\/\/axosnet.info\/?post_type=docs&#038;p=26956"},"modified":"2025-10-15T20:10:13","modified_gmt":"2025-10-15T20:10:13","password":"","slug":"excepciones","status":"publish","type":"docs","link":"https:\/\/axosnet.info\/es\/docs\/excepciones\/","title":{"rendered":"Excepciones"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"26956\" class=\"elementor elementor-26956\" data-elementor-post-type=\"docs\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e0a5c9b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e0a5c9b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dbddd05\" data-id=\"dbddd05\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c661af0 elementor-widget elementor-widget-text-editor\" data-id=\"c661af0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El m\u00f3dulo de Excepciones le permite ver y gestionar los registros de las facturas que, por alguna raz\u00f3n, no se ingresaron correctamente en el portal.<\/p><p>A continuaci\u00f3n, encontrar\u00e1 el paso a paso de los siguientes flujos:<\/p><ul><li><a href=\"#ver-excepciones\">\u00bfC\u00f3mo ver Excepciones?<\/a><\/li><li><a href=\"#regresar-factura-proveedor\">\u00bfC\u00f3mo Regresar Factura a Proveedor?<\/a><\/li><li><a href=\"#regresar-factura-erp\">\u00bfC\u00f3mo Regresar Factura a ERP? <strong><span style=\"color: #993300;\"><em>[Secci\u00f3n en Desarrollo]<\/em><\/span><\/strong><\/a><\/li><li><a href=\"#eliminar-excepciones\">\u00bfC\u00f3mo eliminar Excepciones?<\/a><\/li><li><a href=\"#filtros-busqueda-columnas\">Uso de Filtros\/B\u00fasqueda y Columnas<\/a><\/li><\/ul><h2>\u00a0<\/h2><h3 id=\"ver-excepciones\"><strong>\u00bfC\u00f3mo ver Excepciones?<\/strong><\/h3><ol><li>Ingrese a ACS Management y seleccione la opci\u00f3n Axosnet Cloud Portal.<\/li><\/ol><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/09\/ACP3_FACTURAS_EXCEPCIONES_ESP_0.png\" \/><\/p><ol start=\"2\"><li>Al entrar a ACP seleccione el cliente con el que desea trabajar.<\/li><\/ol><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/09\/ACP3_FACTURAS_EXCEPCIONES_ESP_1-1.png\" \/><\/p><ol start=\"3\"><li>Dentro de ACP 3 seleccione la opci\u00f3n \u201cFacturas\u201d en el men\u00fa lateral izquierdo.<\/li><\/ol><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/09\/ACP3_FACTURAS_EXCEPCIONES_ESP_2-1.png\" \/><\/p><ol start=\"4\"><li>Seleccione \u201cExcepciones\u201d.<\/li><\/ol><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/09\/ACP3_FACTURAS_EXCEPCIONES_ESP_3-1.png\" \/><\/p><ol start=\"5\"><li>En esta subsecci\u00f3n se consultan los registros de las facturas que no fueron ingresadas correctamente mediante:<\/li><\/ol><ul><li style=\"list-style-type: none;\"><ul><li>Ingreso por API<\/li><li>Ingreso por portal (Solo facturas extranjeras o solo PDF)<\/li><li>Ingreso a ERP (Cuando el estatus en SAP es \u201cNO INGRESADA\u201d)<\/li><\/ul><\/li><\/ul><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/09\/ACP3_FACTURAS_EXCEPCIONES_ESP_4-1.png\" \/><\/p><ol start=\"6\"><li>Recibir\u00e1 una notificaci\u00f3n de excepci\u00f3n \u00fanicamente si la factura no fue ingresada a ERP (SAP).<\/li><\/ol><p><strong>Nota:<\/strong> Cuando se devuelve una factura al proveedor, este recibir\u00e1 una notificaci\u00f3n. Para que el proveedor reciba esta notificaci\u00f3n, es necesario realizar la configuraci\u00f3n indicada en el manual <a href=\"https:\/\/axosnet.info\/es\/docs\/configuracion-de-advertencias\/#configurar-advertencia\" target=\"_blank\" rel=\"noopener noreferrer\">Configuraci\u00f3n de Advertencias<\/a>.<\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/09\/ACP3_FACTURAS_EXCEPCIONES_ESP_5-1.png\" \/><\/p><p><strong>Nota:<\/strong> Puede ver un icono en la columna de &#8220;Mensaje&#8221; que le proporcionar\u00e1 detalles sobre por qu\u00e9 la factura est\u00e1 en excepciones.<\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/09\/ACP3_FACTURAS_EXCEPCIONES_ESP_6-1.png\" \/><br \/><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/09\/ACP3_FACTURAS_EXCEPCIONES_ESP_7.png\" \/><\/p><h2>\u00a0<\/h2><h3 id=\"regresar-factura-proveedor\"><strong>\u00bfC\u00f3mo Regresar Factura a Proveedor?<\/strong><\/h3><p>Esta funci\u00f3n permite al cliente devolver una factura al proveedor si presenta errores o requiere correcciones. El icono de detalle muestra la informaci\u00f3n y las razones espec\u00edficas por las que la factura es devuelta.<\/p><p><strong>IMPORTANTE:<\/strong> Esta funci\u00f3n s\u00f3lo est\u00e1 disponible para los usuarios de CLIENTE; los usuarios de PROVEEDOR no pueden ver los botones pero s\u00ed pueden ver las excepciones como se indica en la secci\u00f3n <a href=\"#ver-excepciones\">\u201c\u00bfC\u00f3mo ver Excepciones?\u201d<\/a><\/p><ol><li>Como cliente, desde la lista de Excepciones, seleccione la casilla de la factura que desea regresar.<\/li><\/ol><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/09\/ACP3_FACTURAS_EXCEPCIONES_ESP_8.png\" \/><\/p><p><strong>Nota:<\/strong> Puede ver un icono en la columna de &#8220;Mensaje&#8221; que le proporcionar\u00e1 detalles sobre el motivo de la excepci\u00f3n.<\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/09\/ACP3_FACTURAS_EXCEPCIONES_ESP_9.png\" \/><br \/><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/09\/ACP3_FACTURAS_EXCEPCIONES_ESP_10.png\" \/><\/p><ol start=\"2\"><li>Haga clic en el bot\u00f3n \u201cENVIAR A PROVEEDOR\u201d (este bot\u00f3n se habilitar\u00e1 al seleccionar la casilla de la factura).<\/li><\/ol><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/09\/ACP3_FACTURAS_EXCEPCIONES_ESP_11.png\" \/><\/p><ol start=\"3\"><li>Escriba el motivo de la devoluci\u00f3n y haga clic en &#8220;ACEPTAR&#8221; para confirmar.<\/li><\/ol><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/09\/ACP3_FACTURAS_EXCEPCIONES_ESP_12.png\" \/><\/p><ol start=\"4\"><li>Confirme la acci\u00f3n en la ventana emergente haciendo clic en &#8220;CONFIRMAR&#8221;.<\/li><\/ol><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/09\/ACP3_FACTURAS_EXCEPCIONES_ESP_13.png\" \/><\/p><p><strong>Nota:<\/strong> Cuando se devuelve una factura al proveedor, este recibir\u00e1 una notificaci\u00f3n. Para que el proveedor reciba esta notificaci\u00f3n, es necesario realizar la configuraci\u00f3n indicada en el manual <a href=\"https:\/\/axosnet.info\/es\/docs\/configuracion-de-advertencias\/#configurar-advertencia\" target=\"_blank\" rel=\"noopener noreferrer\">Configuraci\u00f3n de Advertencias<\/a>.<\/p><h2>\u00a0<\/h2><h3 id=\"regresar-factura-erp\"><strong>\u00bfC\u00f3mo Regresar Factura a ERP?<\/strong><\/h3><p><em>Esta secci\u00f3n se encuentra en proceso de desarrollo. Por ahora no se ver\u00e1 activo el bot\u00f3n correspondiente.<\/em><\/p><p><strong>IMPORTANTE:<\/strong> Esta funci\u00f3n s\u00f3lo estar\u00e1 disponible para los usuarios de CLIENTE; los usuarios de PROVEEDOR no pueden ver los botones pero s\u00ed las excepciones como se indica en la secci\u00f3n <a href=\"#ver-excepciones\">\u201c\u00bfC\u00f3mo ver Excepciones?\u201d<\/a><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/09\/ACP3_FACTURAS_EXCEPCIONES_ESP_14.png\" \/><\/p><h2>\u00a0<\/h2><h3 id=\"eliminar-excepciones\"><strong>\u00bfC\u00f3mo eliminar Excepciones?<\/strong><\/h3><ol><li>Del listado que se muestra seleccione la casilla de la factura que desea eliminar.<\/li><\/ol><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/09\/ACP3_FACTURAS_EXCEPCIONES_ESP_15.png\" \/><\/p><ol start=\"2\"><li>Haga clic en el bot\u00f3n \u201cELIMINAR\u201d que se habilit\u00f3 al seleccionar la factura.<\/li><\/ol><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/09\/ACP3_FACTURAS_EXCEPCIONES_ESP_16.png\" \/><\/p><ol start=\"3\"><li>Haga clic en \u201cACEPTAR\u201d para confirmar.<\/li><\/ol><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/09\/ACP3_FACTURAS_EXCEPCIONES_ESP_17.png\" \/><\/p><h2>\u00a0<\/h2><h3 id=\"filtros-busqueda-columnas\"><strong>Uso de Filtros\/B\u00fasqueda y Columnas<\/strong><\/h3><p>En la secci\u00f3n de \u201cExcepciones\u201d puede buscar usando filtros u ocultar\/mostrar columnas seg\u00fan sea necesario.<br \/><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/09\/ACP3_FACTURAS_EXCEPCIONES_ESP_18.png\" \/><\/p><p>Por medio de la opci\u00f3n Columnas, use el selector para adecuar las columnas seg\u00fan sea requerido.<\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/09\/ACP3_FACTURAS_EXCEPCIONES_ESP_19.png\" \/><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>El m\u00f3dulo de Excepciones le permite ver y gestionar los registros de las facturas que, por alguna raz\u00f3n, no se ingresaron correctamente en el portal. A continuaci\u00f3n, encontrar\u00e1 el paso a paso de los siguientes flujos: \u00bfC\u00f3mo ver Excepciones? \u00bfC\u00f3mo Regresar Factura a Proveedor? \u00bfC\u00f3mo Regresar Factura a ERP? [Secci\u00f3n en Desarrollo] \u00bfC\u00f3mo eliminar Excepciones? [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":"","footnotes":""},"doc_category":[457],"doc_tag":[],"knowledge_base":[440],"class_list":["post-26956","docs","type-docs","status-publish","hentry","doc_category-invoices-es","knowledge_base-axosnet-cloud-portal-3-es"],"year_month":"2026-05","word_count":569,"total_views":"26","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"Maria Morales","author_nicename":"mmorales","author_url":"https:\/\/axosnet.info\/es\/author\/mmorales\/"},"doc_category_info":[{"term_name":"Facturas","term_url":"https:\/\/axosnet.info\/es\/docs\/axosnet-cloud-portal-3-es\/invoices-es\/"}],"doc_tag_info":[],"knowledge_base_info":[{"term_name":"Axosnet Cloud Portal 3.0","term_url":"https:\/\/axosnet.info\/es\/docs\/axosnet-cloud-portal-3-es\/","term_slug":"axosnet-cloud-portal-3-es"}],"knowledge_base_slug":["axosnet-cloud-portal-3-es"],"_links":{"self":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/26956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/comments?post=26956"}],"version-history":[{"count":46,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/26956\/revisions"}],"predecessor-version":[{"id":38173,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/26956\/revisions\/38173"}],"wp:attachment":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/media?parent=26956"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/doc_category?post=26956"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/doc_tag?post=26956"},{"taxonomy":"knowledge_base","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/knowledge_base?post=26956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}