{"id":20486,"date":"2024-07-23T17:56:03","date_gmt":"2024-07-23T17:56:03","guid":{"rendered":"https:\/\/axosnet.info\/?post_type=docs&#038;p=20486"},"modified":"2024-07-23T23:18:13","modified_gmt":"2024-07-23T23:18:13","password":"","slug":"actualizar-contrasena","status":"publish","type":"docs","link":"https:\/\/axosnet.info\/es\/docs\/actualizar-contrasena\/","title":{"rendered":"Actualizar Mi Contrase\u00f1a"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"20486\" class=\"elementor elementor-20486\" data-elementor-post-type=\"docs\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f527e13 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f527e13\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-89e9470\" data-id=\"89e9470\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d8d21b elementor-widget elementor-widget-text-editor\" data-id=\"6d8d21b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Si lo requiere, desde la secci\u00f3n de <strong>Mi cuenta<\/strong>, podr\u00e1 actualizar la contrase\u00f1a de acceso a ACS.<\/p><p>1. Haga clic sobre el \u00edcono de la secci\u00f3n <strong>&#8220;Contrase\u00f1a&#8221;.<img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2024\/07\/ACS.B.07-SPA_01.png\" width=\"1919\" height=\"894\" \/><\/strong><\/p><p>\u00a0<\/p><p>2. Ingrese la contrase\u00f1a Anterior, la contrase\u00f1a nueva y la confirmaci\u00f3n de la misma. <img decoding=\"async\" class=\"alignnone size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2024\/07\/ACS.B.07-SPA_02.png\" width=\"1919\" height=\"885\" \/><\/p><p><strong>Nota:\u00a0<\/strong>Para tener una actualizaci\u00f3n v\u00e1lida, revise las especificaciones que debe cumplir la contrase\u00f1a que est\u00e1 usted registrando.<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>3. Haga clic sobre el bot\u00f3n\u00a0<strong>&#8220;Guardar&#8221;<img decoding=\"async\" class=\"alignnone size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2024\/07\/ACS.B.07-SPA_03.png\" width=\"1919\" height=\"891\" \/><\/strong><\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>4. La p\u00e1gina le notificar\u00e1 que la contrase\u00f1a se actualiz\u00f3 correctamente.<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2024\/07\/ACS.B.07-SPA_04.png\" width=\"1919\" height=\"886\" \/><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Si lo requiere, desde la secci\u00f3n de Mi cuenta, podr\u00e1 actualizar la contrase\u00f1a de acceso a ACS. 1. Haga clic sobre el \u00edcono de la secci\u00f3n &#8220;Contrase\u00f1a&#8221;. \u00a0 2. Ingrese la contrase\u00f1a Anterior, la contrase\u00f1a nueva y la confirmaci\u00f3n de la misma. Nota:\u00a0Para tener una actualizaci\u00f3n v\u00e1lida, revise las especificaciones que debe cumplir la contrase\u00f1a [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":"","footnotes":""},"doc_category":[364],"doc_tag":[],"knowledge_base":[153],"class_list":["post-20486","docs","type-docs","status-publish","hentry","doc_category-gestion-de-mi-cuenta","knowledge_base-es-axosnet-cloud-solutions"],"year_month":"2026-07","word_count":86,"total_views":"48","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"Maria Morales","author_nicename":"mmorales","author_url":"https:\/\/axosnet.info\/es\/author\/mmorales\/"},"doc_category_info":[{"term_name":"Gesti\u00f3n de Mi cuenta","term_url":"https:\/\/axosnet.info\/es\/docs\/es-axosnet-cloud-solutions\/gestion-de-mi-cuenta\/"}],"doc_tag_info":[],"knowledge_base_info":[{"term_name":"Axosnet Cloud Solutions (ACS)","term_url":"https:\/\/axosnet.info\/es\/docs\/es-axosnet-cloud-solutions\/","term_slug":"es-axosnet-cloud-solutions"}],"knowledge_base_slug":["es-axosnet-cloud-solutions"],"_links":{"self":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/20486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/comments?post=20486"}],"version-history":[{"count":5,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/20486\/revisions"}],"predecessor-version":[{"id":20579,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/20486\/revisions\/20579"}],"wp:attachment":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/media?parent=20486"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/doc_category?post=20486"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/doc_tag?post=20486"},{"taxonomy":"knowledge_base","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/knowledge_base?post=20486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}