{"id":18569,"date":"2024-05-22T16:33:42","date_gmt":"2024-05-22T16:33:42","guid":{"rendered":"https:\/\/axosnet.info\/?post_type=docs&#038;p=18569"},"modified":"2026-06-16T18:02:06","modified_gmt":"2026-06-16T18:02:06","password":"","slug":"completar-registro","status":"publish","type":"docs","link":"https:\/\/axosnet.info\/es\/docs\/completar-registro\/","title":{"rendered":"Completar Registro"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"18569\" class=\"elementor elementor-18569 elementor-18754\" data-elementor-post-type=\"docs\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bbdb5e4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bbdb5e4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6c16afc\" data-id=\"6c16afc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c495b56 elementor-widget elementor-widget-text-editor\" data-id=\"c495b56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Es necesario que el administrador o en su defecto el Propietario de Cuenta, complete un registro ingresando la informaci\u00f3n requerida para activar la cuenta correctamente.<\/span><\/p><p><span style=\"font-weight: 400;\">a) Inicie sesi\u00f3n en ACS y haga clic sobre ACS Management.<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/06\/com_registro_1-1.png\" \/><\/p><p>b) <span style=\"font-weight: 400;\">Haga clic sobre Comenzar.<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/06\/com_registro_2-1.png\" \/><\/p><p>c) <span style=\"font-weight: 400;\">Se mostrar\u00e1n los pasos solicitados para completar el registro de la cuenta del\u00a0 negocio en ACS.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">En el paso 1, verifique el Nombre de la cuenta o en su defecto, haga clic sobre el campo para editarlo y finalmente haga clic sobre \u201cGuardar nombre de cuenta\u201d.<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/06\/com_registro_3-1.png\" \/><\/p><p>d) <span style=\"font-weight: 400;\">Haga clic sobre el Logo de \u201cAxosnet\u201d para cambiarlo, ya\u00a0 que est\u00e1 por default.\u00a0<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/06\/com_registro_4-1.png\" \/><\/p><p>e) <span style=\"font-weight: 400;\">Haga clic sobre el \u00edcono de \u201cEliminar\u201d para borrar el logo de Axosnet.<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/06\/com_registro_5-1.png\" \/><\/p><p>f) <span style=\"font-weight: 400;\">Cargue la im\u00e1gen del Logo correspondiente a su compa\u00f1\u00eda si as\u00ed lo requiere y haga clic sobre \u201cGuardar\u201d.<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/06\/com_registro_6-1.png\" \/><\/p><p>g) <span style=\"font-weight: 400;\">Haga clic sobre \u201csiguiente&#8221;.<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/06\/com_registro_7-1.png\" \/><\/p><h4><strong>2.1 Datos del Propietario de Cuenta<\/strong><\/h4><p><span style=\"font-weight: 400;\">A partir de este paso, se podr\u00e1n realizar 2 formas de llevar a cabo el registro de la cuenta, ya sea de manera provisional o como cuenta definitiva.<\/span><\/p><h4><strong>2.1.1 Como cuenta definitiva (Cuando es Propietario de Cuenta)<\/strong><\/h4><p><span style=\"font-weight: 400;\">a) Seleccione el check de \u201cS\u00cd\u201d, si es usted el Propietario de Cuenta.<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/06\/com_registro_8-1.png\" \/><\/p><p><span style=\"font-weight: 400;\">b) Registre m\u00ednimo dos Administradores de cuenta y haga clic sobre \u201cSiguiente\u201d.<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/06\/com_registro_9-1.png\" \/><\/p><p><b>Nota: <\/b><span style=\"font-weight: 400;\">Si son considerados como personas de contacto, active la opci\u00f3n para que la informaci\u00f3n del registro se desplace al siguiente paso.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">c) Para el paso de \u201cPersonas de contacto\u201d, puede registrar o dejar vac\u00edo el formulario, ya que es una secci\u00f3n opcional. Haga clic sobre Siguiente.<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/06\/com_registro_10-1.png\" \/><\/p><p><b>Nota: <\/b><span style=\"font-weight: 400;\">Si tiene registradas a \u201cpersonas de contacto\u201d, podr\u00e1 activar el check de \u201c\u00bfEs delegado?\u201d si as\u00ed lo requiere.<\/span><\/p><p><span style=\"font-weight: 400;\">d) Dentro del paso \u201cDelegados de Administraci\u00f3n de cuenta\u201d, puede registrar o dejar vac\u00edo el formulario, ya que es una secci\u00f3n opcional. Haga clic sobre Siguiente.<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/06\/com_registro_11-1.png\" \/><\/p><p><span style=\"font-weight: 400;\">e) Registre los Datos Generales de la compa\u00f1\u00eda, los datos Obligatorios son resaltados con un asterisco \u201c*\u201d. Haga clic sobre Siguiente.<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/06\/com_registro_12-1.png\" \/><\/p><p><b>Nota:<\/b><span style=\"font-weight: 400;\"> Dentro de los campos de configuraci\u00f3n, usted cuenta con las siguientes opciones:<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Direcci\u00f3n:<\/b><span style=\"font-weight: 400;\"> Permite localizar la ubicaci\u00f3n exacta realizando una b\u00fasqueda por el nombre de la empresa.<\/span><\/li><\/ul><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2026\/06\/imagen-7.png\" \/><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Dominios Oficiales:<\/b><span style=\"font-weight: 400;\"> Ofrece la flexibilidad de incluir m\u00faltiples dominios, los cuales deben ser ingresados y separados mediante el uso de comas (\u201c,\u201d).<\/span><\/li><\/ul><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2026\/06\/imagen-8.png\" \/><\/p><p><b>IMPORTANTE<\/b>: El campo &#8220;Dominios oficiales&#8221; est\u00e1 indicado como opcional ya que no tiene impacto si se deja vac\u00edo, sin embargo si decide especificar un dominio, el sistema validar\u00e1 que los correos que se ingresen\/registren pertenezcan a ese dominio. Si desea agregar mas de un dominio deber\u00e1 separlos por coma (,). <b>Ejemplo<\/b>: el dominio del correo <i>juanperez@empresa.com.mx<\/i> es <i>empresa.com.mx<\/i><\/p><div>\u00a0<\/div><p><span style=\"font-weight: 400;\">f) Se muestra el \u201cRes\u00famen de la informaci\u00f3n&#8221;, verifique los datos anteriormente ingresados y haga clic sobre Siguiente.<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/06\/com_registro_13-1.png\" \/><\/p><p><span style=\"font-weight: 400;\">g) Finalmente, podr\u00e1 identificar los T\u00c9RMINOS Y CONDICIONES DE ALTA DE CUENTA, lea, acepte y haga clic en Confirmar.<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/06\/com_registro_14-1.png\" \/><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/06\/com_registro_15-1.png\" \/><\/p><p><span style=\"font-weight: 400;\">h) Propietario de Cuenta y Administrador recibir\u00e1n un correo de confirmaci\u00f3n de su cuenta activa.<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/06\/prov-registro-1.1.png\" \/><\/p><p><b>Nota: <\/b><span style=\"font-weight: 400;\">El estatus de la cuenta de ACS Management del Propietario de Cuenta y Administradores ser\u00e1 \u201cActiva\u201d al momento de que el Propietario concluya con el registro y acepte los T\u00e9rminos y condiciones, lo que indica que la cuenta se ha creado de manera definitiva en la plataforma.\u00a0<\/span><\/p><h4><strong>2.1.2 Como cuenta provisional (Cuando no es Propietario de Cuenta)<\/strong><\/h4><p><span style=\"font-weight: 400;\">a) Seleccione el check de \u201cNO\u201d, si usted No es el Propietario de Cuenta.<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/06\/provisional-registro1.png\" \/><\/p><p>b) <span style=\"font-weight: 400;\">Ingrese la informaci\u00f3n del usuario que cumple con ese rol y haga clic sobre \u201cSiguiente&#8221;.<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/06\/provisional-registro2.png\" \/><\/p><p>c) <span style=\"font-weight: 400;\">Dentro del paso 3 \u201cAdministradores de cuenta\u201d, registre por lo menos un usuario m\u00e1s, ya que el registro del Propietario de Cuenta propuesto pasar\u00e1 por default a esta secci\u00f3n.<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/06\/provisional-registro3.png\" \/><\/p><p><b>Nota: <\/b><span style=\"font-weight: 400;\">Si son considerados como personas de contacto, active la opci\u00f3n para que la informaci\u00f3n del registro se desplace al siguiente paso. <\/span><\/p><p>d) <span style=\"font-weight: 400;\">Para el paso de \u201cPersonas de contacto\u201d, puede registrar o dejar vac\u00edo el formulario, ya que es una secci\u00f3n opcional. Haga clic sobre Siguiente.<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/06\/provisional-registro4.png\" \/><\/p><p><b>Nota: <\/b><span style=\"font-weight: 400;\">Si tiene registradas a \u201cpersonas de contacto\u201d, podr\u00e1 activar el check de \u201c\u00bfEs delegado?\u201d si as\u00ed lo requiere.<\/span><\/p><p>e) <span style=\"font-weight: 400;\">Dentro del paso \u201cDelegados de Administraci\u00f3n de cuenta\u201d, puede registrar o dejar vac\u00edo el formulario, ya que es una secci\u00f3n opcional. Haga clic sobre Siguiente.<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/06\/provisional-registro5.png\" \/><\/p><p><b>Nota: <\/b><span style=\"font-weight: 400;\">Si son considerados como personas de contacto, active la opci\u00f3n para que el registro se desplace al siguiente paso.<\/span><\/p><p>f) <span style=\"font-weight: 400;\">Registre los Datos Generales de la compa\u00f1\u00eda, los datos Obligatorios son resaltados con un asterisco \u201c*\u201d. Haga clic sobre Siguiente.<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/06\/provisional-registro6.png\" \/><\/p><p>g) <span style=\"font-weight: 400;\">Se muestra el \u201cRes\u00famen de la informaci\u00f3n&#8221;, verifique los datos anteriormente ingresados y haga clic sobre Siguiente.<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/06\/provisional-registro7.png\" \/><\/p><p>h) <span style=\"font-weight: 400;\">Finalmente, podr\u00e1 identificar los T\u00c9RMINOS Y CONDICIONES PROVISIONALES DE ALTA DE CUENTA, lea, acepte y haga clic en Confirmar.<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/06\/provisional-registro8.png\" \/><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/06\/provisional-registro9.png\" \/><\/p><p>i) El <span style=\"font-weight: 400;\">Propietario de Cuenta<\/span><span style=\"font-weight: 400;\"> y Administrador recibir\u00e1n un correo comunicando el Pre Registro de la cuenta.\u00a0<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/06\/provisional-registro10.1.png\" \/><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2025\/06\/provisional-registro11.1.png\" \/><\/p><p><b>Nota: <\/b><span style=\"font-weight: 400;\">El acceso a ACS Management del Propietario de Cuenta y Administradores ser\u00e1 \u201cprovisional\u201d, significa que contar\u00e1 con un periodo de 30 d\u00edas antes de su suspensi\u00f3n si no se llegase a completar el Registro de la cuenta por el Propietario de Cuenta, durante el periodo de 30 d\u00edas el Propietario de Cuenta recibir\u00e1 un recordatorio para el registro formal de los t\u00e9rminos y condiciones para finalizar el registro de cuenta pasando de estatus provisional a activa.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Es necesario que el administrador o en su defecto el Propietario de Cuenta, complete un registro ingresando la informaci\u00f3n requerida para activar la cuenta correctamente. a) Inicie sesi\u00f3n en ACS y haga clic sobre ACS Management. b) Haga clic sobre Comenzar. c) Se mostrar\u00e1n los pasos solicitados para completar el registro de la cuenta del\u00a0 [&hellip;]<\/p>\n","protected":false},"author":36,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":"","footnotes":""},"doc_category":[267],"doc_tag":[],"knowledge_base":[153],"class_list":["post-18569","docs","type-docs","status-publish","hentry","doc_category-autorregistro","knowledge_base-es-axosnet-cloud-solutions"],"year_month":"2026-07","word_count":905,"total_views":"1095","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"Daniel Galindo","author_nicename":"dgalindo","author_url":"https:\/\/axosnet.info\/es\/author\/dgalindo\/"},"doc_category_info":[{"term_name":"Autorregistro","term_url":"https:\/\/axosnet.info\/es\/docs\/es-axosnet-cloud-solutions\/autorregistro\/"}],"doc_tag_info":[],"knowledge_base_info":[{"term_name":"Axosnet Cloud Solutions (ACS)","term_url":"https:\/\/axosnet.info\/es\/docs\/es-axosnet-cloud-solutions\/","term_slug":"es-axosnet-cloud-solutions"}],"knowledge_base_slug":["es-axosnet-cloud-solutions"],"_links":{"self":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/18569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/comments?post=18569"}],"version-history":[{"count":23,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/18569\/revisions"}],"predecessor-version":[{"id":42998,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/18569\/revisions\/42998"}],"wp:attachment":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/media?parent=18569"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/doc_category?post=18569"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/doc_tag?post=18569"},{"taxonomy":"knowledge_base","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/knowledge_base?post=18569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}