{"id":17060,"date":"2024-04-15T21:28:21","date_gmt":"2024-04-15T21:28:21","guid":{"rendered":"https:\/\/axosnet.info\/?post_type=docs&#038;p=17060"},"modified":"2024-04-15T21:25:27","modified_gmt":"2024-04-15T21:25:27","password":"","slug":"editar-un-equipo","status":"publish","type":"docs","link":"https:\/\/axosnet.info\/es\/docs\/editar-un-equipo\/","title":{"rendered":"Editar un equipo"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"17060\" class=\"elementor elementor-17060 elementor-16891\" data-elementor-post-type=\"docs\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-602a984 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"602a984\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-741599eb\" data-id=\"741599eb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e113c4b elementor-widget elementor-widget-text-editor\" data-id=\"5e113c4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<ol class=\"\">\n<li class=\"\">Ingrese a la secci\u00f3n &#8220;Usuarios y Permisos&#8221;.<br \/><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2024\/04\/ACS.I.04-SPA_01.png\" width=\"1919\" height=\"838\" \/><\/li>\n\n<li class=\"\">En la secci\u00f3n de &#8220;Usuarios&#8221;, haga clic en el icono &#8220;&gt;&#8221;.<br \/><img decoding=\"async\" class=\"alignnone size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2024\/04\/ACS.I.04-SPA_02.png\" width=\"1896\" height=\"838\" \/><\/li>\n\n<li class=\"\">Haga clic en &#8220;Administrar unidades organizacionales&#8221; para gestionar equipos en la Estructura Organizacional.<br \/><img decoding=\"async\" class=\"alignnone size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2024\/04\/ACS.I.04-SPA_03.png\" width=\"1896\" height=\"839\" \/><\/li>\n\n<li class=\"\">Para visualizar los departamentos actualmente registrados, haga clic en el icono &#8220;&gt;&#8221; de la compa\u00f1\u00eda que desee.<br \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2024\/04\/ACS.I.04-SPA_04.png\" width=\"1896\" height=\"838\" \/><\/li>\n\n<li class=\"\">Haga clic en el icono de edici\u00f3n (<strong>\ud83d\udd8a<\/strong>) del equipo que desea editar.<br \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2024\/04\/ACS.I.04-SPA_05.png\" width=\"1896\" height=\"838\" \/><\/li>\n\n<li class=\"\">Modifique los datos requeridos y haga clic en el bot\u00f3n &#8220;Guardar&#8221;.<br \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2024\/04\/ACS.I.04-SPA_06.png\" width=\"1896\" height=\"840\" \/><\/li>\n\n<li class=\"\">Se mostrar\u00e1 un mensaje de edici\u00f3n exitosa junto con el registro del departamento actualizado.<br \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2024\/04\/ACS.I.04-SPA_07.png\" width=\"1896\" height=\"839\" \/><\/li>\n<\/ol>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ingrese a la secci\u00f3n &#8220;Usuarios y Permisos&#8221;. En la secci\u00f3n de &#8220;Usuarios&#8221;, haga clic en el icono &#8220;&gt;&#8221;. Haga clic en &#8220;Administrar unidades organizacionales&#8221; para gestionar equipos en la Estructura Organizacional. Para visualizar los departamentos actualmente registrados, haga clic en el icono &#8220;&gt;&#8221; de la compa\u00f1\u00eda que desee. Haga clic en el icono de edici\u00f3n [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":"","footnotes":""},"doc_category":[253],"doc_tag":[],"knowledge_base":[153],"class_list":["post-17060","docs","type-docs","status-publish","hentry","doc_category-gestion-estructura-organizacional","knowledge_base-es-axosnet-cloud-solutions"],"year_month":"2026-07","word_count":91,"total_views":"54","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"Maria Morales","author_nicename":"mmorales","author_url":"https:\/\/axosnet.info\/es\/author\/mmorales\/"},"doc_category_info":[{"term_name":"Gesti\u00f3n Estructura Organizacional","term_url":"https:\/\/axosnet.info\/es\/docs\/es-axosnet-cloud-solutions\/gestion-estructura-organizacional\/"}],"doc_tag_info":[],"knowledge_base_info":[{"term_name":"Axosnet Cloud Solutions (ACS)","term_url":"https:\/\/axosnet.info\/es\/docs\/es-axosnet-cloud-solutions\/","term_slug":"es-axosnet-cloud-solutions"}],"knowledge_base_slug":["es-axosnet-cloud-solutions"],"_links":{"self":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/17060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/comments?post=17060"}],"version-history":[{"count":6,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/17060\/revisions"}],"predecessor-version":[{"id":29465,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/17060\/revisions\/29465"}],"wp:attachment":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/media?parent=17060"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/doc_category?post=17060"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/doc_tag?post=17060"},{"taxonomy":"knowledge_base","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/knowledge_base?post=17060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}