{"id":11795,"date":"2023-01-11T19:47:40","date_gmt":"2023-01-11T19:47:40","guid":{"rendered":"https:\/\/rfiii.com\/?post_type=docs&#038;p=11795"},"modified":"2025-02-12T22:52:24","modified_gmt":"2025-02-12T22:52:24","password":"","slug":"edicion-de-una-aplicacion","status":"publish","type":"docs","link":"https:\/\/axosnet.info\/es\/docs\/edicion-de-una-aplicacion\/","title":{"rendered":"Edici\u00f3n de una aplicaci\u00f3n"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"11795\" class=\"elementor elementor-11795 elementor-3573\" data-elementor-post-type=\"docs\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7913eeb8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7913eeb8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5f40d532\" data-id=\"5f40d532\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38bacbfd elementor-widget elementor-widget-text-editor\" data-id=\"38bacbfd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Siga estos pasos para modificar el contenido de una aplicaci\u00f3n.<\/span><\/p><p><span style=\"font-weight: 400;\">1. Ingresar a ACS Management.<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2024\/08\/ACS.E.02-SPA-01.png\" \/><\/p><p><span style=\"font-weight: 400;\">2. Seleccione \u201cServicios Web\u201d.<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2024\/08\/ACS.E.02-SPA-02.png\" \/><\/p><p><span style=\"font-weight: 400;\">3. Haga clic en el bot\u00f3n \u201cDetalles\u201d.<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2024\/08\/ACS.E.02-SPA-03.png\" \/><\/p><p><span style=\"font-weight: 400;\">4. En esta secci\u00f3n se puede:<\/span><\/p><p><b>a) Editar los campos:<\/b><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u00a0Nombre de la aplicaci\u00f3n<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u00a0Alcances<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u00a0Descripci\u00f3n<\/span><\/li><\/ul><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2024\/08\/ACS.E.02-SPA-04-a-1.png\" \/><\/p><p><span style=\"font-weight: 400;\">1.Una vez modificada la informaci\u00f3n haga clic en \u201cGUARDAR\u201d.<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2024\/08\/ACS.E.02-SPA-04-a-2.png\" \/><\/p><p><span style=\"font-weight: 400;\">2. Se muestra un mensaje de notificaci\u00f3n indicando que los datos modificados se guardaron exitosamente.<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2024\/08\/ACS.E.02-SPA-04-a-3.png\" \/><\/p><p><b>b) Resetear claves:<\/b><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2024\/08\/ACS.E.02-SPA-04-b-1.png\" \/><\/p><p><span style=\"font-weight: 400;\">1. Si desea restablecer las claves para esta aplicaci\u00f3n, haga clic en el bot\u00f3n \u201cRESETEAR CLAVES\u201d.<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2024\/08\/ACS.E.02-SPA-04-b-2.png\" \/><\/p><p><span style=\"font-weight: 400;\">2. Para confirmar la operaci\u00f3n, haga clic en el bot\u00f3n \u201cACEPTAR\u201d.\u00a0<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2024\/08\/ACS.E.02-SPA-04-b-3.png\" \/><\/p><p><span style=\"font-weight: 400;\">3. Se muestra un mensaje de confirmaci\u00f3n que indica que se modificaron las claves.<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2024\/08\/ACS.E.02-SPA-04-b-4.png\" \/><\/p><p><span style=\"font-weight: 400;\">4. Para mantener los cambios haga clic en \u201cGUARDAR\u201d.<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2024\/08\/ACS.E.02-SPA-04-b-5.png\" \/><\/p><p><span style=\"font-weight: 400;\">5. Se muestra un mensaje de notificaci\u00f3n indicando que los datos modificados se guardaron exitosamente.<\/span><\/p><p><img decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2024\/08\/ACS.E.02-SPA-04-b-6.png\" \/><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Siga estos pasos para modificar el contenido de una aplicaci\u00f3n. 1. Ingresar a ACS Management. 2. Seleccione \u201cServicios Web\u201d. 3. Haga clic en el bot\u00f3n \u201cDetalles\u201d. 4. En esta secci\u00f3n se puede: a) Editar los campos: \u00a0Nombre de la aplicaci\u00f3n \u00a0Alcances \u00a0Descripci\u00f3n 1.Una vez modificada la informaci\u00f3n haga clic en \u201cGUARDAR\u201d. 2. Se muestra un [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":"","footnotes":""},"doc_category":[167],"doc_tag":[],"knowledge_base":[153],"class_list":["post-11795","docs","type-docs","status-publish","hentry","doc_category-es-gestion-de-servicios-web","knowledge_base-es-axosnet-cloud-solutions"],"year_month":"2026-07","word_count":137,"total_views":"90","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"","author_nicename":"","author_url":"https:\/\/axosnet.info\/es\/author\/"},"doc_category_info":[{"term_name":"Administraci\u00f3n de Servicios Web","term_url":"https:\/\/axosnet.info\/es\/docs\/es-axosnet-cloud-solutions\/es-gestion-de-servicios-web\/"}],"doc_tag_info":[],"knowledge_base_info":[{"term_name":"Axosnet Cloud Solutions (ACS)","term_url":"https:\/\/axosnet.info\/es\/docs\/es-axosnet-cloud-solutions\/","term_slug":"es-axosnet-cloud-solutions"}],"knowledge_base_slug":["es-axosnet-cloud-solutions"],"_links":{"self":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/11795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/comments?post=11795"}],"version-history":[{"count":8,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/11795\/revisions"}],"predecessor-version":[{"id":30565,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/11795\/revisions\/30565"}],"wp:attachment":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/media?parent=11795"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/doc_category?post=11795"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/doc_tag?post=11795"},{"taxonomy":"knowledge_base","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/knowledge_base?post=11795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}