{"id":11715,"date":"2023-01-04T20:30:31","date_gmt":"2023-01-04T20:30:31","guid":{"rendered":"https:\/\/rfiii.com\/?post_type=docs&#038;p=11715"},"modified":"2025-10-15T19:20:55","modified_gmt":"2025-10-15T19:20:55","password":"","slug":"ver-usuarios","status":"publish","type":"docs","link":"https:\/\/axosnet.info\/es\/docs\/ver-usuarios\/","title":{"rendered":"Ver usuarios"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"11715\" class=\"elementor elementor-11715 elementor-2984\" data-elementor-post-type=\"docs\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4489bf2c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4489bf2c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5d733f81\" data-id=\"5d733f81\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64cd77f4 elementor-widget elementor-widget-text-editor\" data-id=\"64cd77f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Los usuarios son todas las personas registradas en ACS y que pertenecen a una cuenta.<\/p><p>Esta secci\u00f3n tiene el objetivo de detallar los pasos para que pueda ubicar a los usuarios que actualmente existen en la cuenta correspondiente.<\/p><p>1. Haga clic en la secci\u00f3n &#8220;<strong>Usuarios y permisos<\/strong>&#8220;.<\/p><p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2024\/07\/ACS.D.01-SPA_01.png\" width=\"1919\" height=\"884\" \/><\/p><p>2. Identificar\u00e1 el listado de los usuarios junto con las siguientes caracter\u00edsticas:<\/p><ul><li>Nombre<\/li><li>Correo electr\u00f3nico<\/li><li>Credenciales: Son las credenciales que el usuario tiene asignadas.<\/li><li>Departamento<\/li><li>Equipo<\/li><li>\u00daltima sesi\u00f3n: Fecha y hora de la ultima conexi\u00f3n del usuario<\/li><li>Estatus<\/li><li>Acciones: Se destacan las tareas de Reenviar Invitaci\u00f3n, Eliminar usuario, Ver detalles, Usuario de contacto y <a href=\"https:\/\/axosnet.info\/es\/docs\/restablecer-contrasena\/\">Restablecer Contrase\u00f1a de otro Usuario.<\/a><br \/><img decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2024\/07\/ACS.D.01-SPA_02.png\" width=\"1919\" height=\"887\" \/><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Los usuarios son todas las personas registradas en ACS y que pertenecen a una cuenta. Esta secci\u00f3n tiene el objetivo de detallar los pasos para que pueda ubicar a los usuarios que actualmente existen en la cuenta correspondiente. 1. Haga clic en la secci\u00f3n &#8220;Usuarios y permisos&#8220;. 2. Identificar\u00e1 el listado de los usuarios junto [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":"","footnotes":""},"doc_category":[166],"doc_tag":[],"knowledge_base":[153],"class_list":["post-11715","docs","type-docs","status-publish","hentry","doc_category-es-gestion-de-usuarios","knowledge_base-es-axosnet-cloud-solutions"],"year_month":"2026-07","word_count":107,"total_views":"197","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"","author_nicename":"","author_url":"https:\/\/axosnet.info\/es\/author\/"},"doc_category_info":[{"term_name":"Administraci\u00f3n de Usuarios","term_url":"https:\/\/axosnet.info\/es\/docs\/es-axosnet-cloud-solutions\/es-gestion-de-usuarios\/"}],"doc_tag_info":[],"knowledge_base_info":[{"term_name":"Axosnet Cloud Solutions (ACS)","term_url":"https:\/\/axosnet.info\/es\/docs\/es-axosnet-cloud-solutions\/","term_slug":"es-axosnet-cloud-solutions"}],"knowledge_base_slug":["es-axosnet-cloud-solutions"],"_links":{"self":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/11715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/comments?post=11715"}],"version-history":[{"count":8,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/11715\/revisions"}],"predecessor-version":[{"id":38032,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/11715\/revisions\/38032"}],"wp:attachment":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/media?parent=11715"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/doc_category?post=11715"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/doc_tag?post=11715"},{"taxonomy":"knowledge_base","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/knowledge_base?post=11715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}