{"id":11021,"date":"2023-01-19T22:39:42","date_gmt":"2023-01-19T22:39:42","guid":{"rendered":"https:\/\/rfiii.com\/?post_type=docs&#038;p=11021"},"modified":"2026-04-06T22:58:02","modified_gmt":"2026-04-06T22:58:02","password":"","slug":"primer-acceso","status":"publish","type":"docs","link":"https:\/\/axosnet.info\/es\/docs\/primer-acceso\/","title":{"rendered":"Primer Acceso"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"11021\" class=\"elementor elementor-11021 elementor-4837\" data-elementor-post-type=\"docs\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-757eda10 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"757eda10\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-20b02d45\" data-id=\"20b02d45\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-267750f6 elementor-widget elementor-widget-text-editor\" data-id=\"267750f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Si es la primera vez que inicia sesi\u00f3n, necesitar\u00e1 las credenciales de Axosnet. En caso de no contar con ellos, favor de solicitarlo al administrador de su empresa.<\/strong><\/p><p>1. Al acceder por primera vez a AxosMoney (versi\u00f3n m\u00f3vil o web), la plataforma Axosnet Cloud Solutions (ACS) le enviar\u00e1 un correo electr\u00f3nico que registro para su usuario y una contrase\u00f1a temporal.<\/p><p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/AXM-iOS-A.a.1.jpeg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/AXM-iOS-A.a.1.jpeg\" width=\"281\" height=\"500\" \/><\/a><\/p><p>2. En la aplicaci\u00f3n Axosmoney, ingrese su correo electr\u00f3nico y presione <strong>&#8220;Siguiente&#8221;<\/strong>, despu\u00e9s ingrese la contrase\u00f1a temporal y presione <strong>&#8220;Iniciar sesi\u00f3n&#8221;<\/strong>.<\/p><figure><table style=\"height: 323px;\" width=\"256\"><tbody><tr><td style=\"border-style: none;\"><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/AXM-iOS-A.a.2.1.jpeg\"><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/AXM-iOS-A.a.2.1.jpeg\" width=\"281\" height=\"500\" \/><\/a><\/td><td style=\"border-style: none;\"><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/AXM-iOS-A.a.2.2.jpeg\"><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/AXM-iOS-A.a.2.2.jpeg\" width=\"281\" height=\"500\" \/><\/a><\/td><\/tr><\/tbody><\/table><\/figure><p>3. Capture y confirme su nueva contrase\u00f1a, luego de clic en <strong>&#8220;Aceptar&#8221;<\/strong>.<\/p><p><strong>Nota<\/strong>: Esta pantalla aparece solo cuando es su primer acceso a la aplicaci\u00f3n AxosMoney.<\/p><p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/AXM-iOS-A.a.3.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/AXM-iOS-A.a.3.png\" width=\"281\" height=\"500\" \/><\/a><\/p><p>4. Aparecer\u00e1 un mensaje de \u00e9xito. Haga clic en <strong>&#8220;Entendido&#8221;<\/strong>.<\/p><p><a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/AXM-iOS-A.a.4.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/AXM-iOS-A.a.4.png\" width=\"281\" height=\"500\" \/><\/a><\/p><p>5. Cuando ingresa a la aplicaci\u00f3n AxosMoney, una ventana de ayuda r\u00e1pida explica la funcionalidad que la aplicaci\u00f3n le brinda.<\/p><p>De clic en <strong>&#8220;Siguiente&#8221;<\/strong> hasta llegar nuevamente a la pantalla de Inicio de sesi\u00f3n.<a href=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/AXM-iOS-A.a.5.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2023\/07\/AXM-iOS-A.a.5.jpeg\" width=\"281\" height=\"500\" \/><\/a><\/p><p>6. <span style=\"font-weight: 400;\">Cuando inicie sesi\u00f3n por primera vez, se muestra la pantalla principal de Axosmoney, donde se ubican las tarjetas (o aplicativos) contratados. Dentro de la tarjeta <strong>Expense<\/strong><strong>, <\/strong>de clic sobre &#8220;<strong>Ver detalle&#8221;.<\/strong><\/span><\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2024\/03\/AXI.A.01-SPA_06.jpg\" width=\"281\" height=\"500\" \/><\/p><p><strong>Nota:<\/strong> Las notificaciones que almacena el \u00edcono <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2024\/03\/AXI.A.01-SPA_icon.png\" alt=\"\" width=\"25\" height=\"20\" \/> son del aplicativo en general.<\/p><p>\u00a0<\/p><p>7.\u00a0 La aplicaci\u00f3n <span style=\"font-weight: 400;\">lo guiar\u00e1 con un breve tutorial sobre la funcionalidad de cada secci\u00f3n de Expense (Gastos) en el men\u00fa de la parte inferior de la pantalla. Haga clic en cada paso se\u00f1alado.<\/span><\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2024\/03\/AXI.A.01-SPA_07.jpeg\" width=\"281\" height=\"500\" \/><\/p><p>\u00a0<\/p><p>8.\u00a0 Mientras no est\u00e9 vinculado a SAP Concur, no podr\u00e1 visualizar la pantalla de Inicio de Expense, por lo que el siguiente paso es realizar la autenticaci\u00f3n en Concur para obtener acceso completo a las funciones de gastos.<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/axosnet.info\/wp-content\/uploads\/2024\/03\/AXI.A.01-SPA_08.jpeg\" width=\"281\" height=\"500\" \/><\/p><p><strong>Nota<\/strong>: Para revisar en detalle los pasos para vincular su cuenta a SAP Concur, consulte la secci\u00f3n:<a href=\"https:\/\/axosnet.info\/es\/docs\/enlace-a-sap-concur\/\">ENLACE A SAP CONCUR CON NOMBRE DE USUARIO.<\/a><\/p><p>\u00a0<\/p><p><b>Mensajes<\/b><\/p><figure><table><tbody><tr><td><strong>Mensaje<\/strong><\/td><td><strong>Causa<\/strong><\/td><td><strong>Soluci\u00f3n<\/strong><\/td><\/tr><tr><td>Por favor complete los campos vac\u00edos<\/td><td>Uno de los campos de contrase\u00f1a o ambos estaban vac\u00edos al presionar Aceptar.<\/td><td>Complete los datos en ambos campos de contrase\u00f1a e intente guardar de nuevo.<\/td><\/tr><tr><td>La nueva contrase\u00f1a y la confirmaci\u00f3n deben coincidir<\/td><td>Este mensaje aparece cuando la nueva contrase\u00f1a no coincide con la contrase\u00f1a de confirmaci\u00f3n.<\/td><td>Ingrese la misma contrase\u00f1a en ambos campos e intente guardar de nuevo.<\/td><\/tr><tr><td>La contrase\u00f1a no puede ser la misma que la anterior<\/td><td>Este mensaje aparece cuando ha ingresado la misma contrase\u00f1a que el usuario tiene actualmente.<\/td><td>Ingrese una contrase\u00f1a diferente a la que tiene actualmente registrada el usuario.<\/td><\/tr><tr><td>La contrase\u00f1a se ha cambiado correctamente<\/td><td>Aparece cuando ha guardado exitosamente el cambio de contrase\u00f1a en el primer inicio de sesi\u00f3n.<\/td><td>Presione OK para cerrar el mensaje.<\/td><\/tr><tr><td>Advertencia: No fue posible actualizar su sesi\u00f3n.<\/td><td>No tiene una cuenta vinculada a SAP Concur.<\/td><td>Vincule su cuenta con SAP Concur.<\/td><\/tr><\/tbody><\/table><\/figure>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Si es la primera vez que inicia sesi\u00f3n, necesitar\u00e1 las credenciales de Axosnet. En caso de no contar con ellos, favor de solicitarlo al administrador de su empresa. 1. Al acceder por primera vez a AxosMoney (versi\u00f3n m\u00f3vil o web), la plataforma Axosnet Cloud Solutions (ACS) le enviar\u00e1 un correo electr\u00f3nico que registro para su [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":"","footnotes":""},"doc_category":[186],"doc_tag":[],"knowledge_base":[152],"class_list":["post-11021","docs","type-docs","status-publish","hentry","doc_category-es-amon-i-emp","knowledge_base-es-axosmoney-ios"],"year_month":"2026-07","word_count":470,"total_views":"139","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"Maria Morales","author_nicename":"mmorales","author_url":"https:\/\/axosnet.info\/es\/author\/mmorales\/"},"doc_category_info":[{"term_name":"Comenzando AxosMoney iOS","term_url":"https:\/\/axosnet.info\/es\/docs\/es-axosmoney-ios\/es-amon-i-emp\/"}],"doc_tag_info":[],"knowledge_base_info":[{"term_name":"AxosMoney - iOS","term_url":"https:\/\/axosnet.info\/es\/docs\/es-axosmoney-ios\/","term_slug":"es-axosmoney-ios"}],"knowledge_base_slug":["es-axosmoney-ios"],"_links":{"self":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/11021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/comments?post=11021"}],"version-history":[{"count":5,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/11021\/revisions"}],"predecessor-version":[{"id":16245,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/docs\/11021\/revisions\/16245"}],"wp:attachment":[{"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/media?parent=11021"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/doc_category?post=11021"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/doc_tag?post=11021"},{"taxonomy":"knowledge_base","embeddable":true,"href":"https:\/\/axosnet.info\/es\/wp-json\/wp\/v2\/knowledge_base?post=11021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}